{"id":65586,"date":"2022-07-19T12:29:09","date_gmt":"2022-07-19T10:29:09","guid":{"rendered":"http:\/\/www.veeva.com\/eu\/?page_id=65586"},"modified":"2026-02-13T12:56:33","modified_gmt":"2026-02-13T11:56:33","slug":"news","status":"publish","type":"page","link":"https:\/\/www.veeva.com\/eu\/fr\/news\/","title":{"rendered":"Communiqu\u00e9s de presse"},"content":{"rendered":"<p><a class=\"resource-card\" href=\"https:\/\/www.journaldunet.com\/intelligence-artificielle\/1540625-data-et-leader-d-opinion-un-facteur-determinant-pour-l-innovation-pour-l-industrie-pharmaceutique\/\" target=\"_blank\" rel=\"noopener\"><\/p>\n<div class=\"resource-card__text\">\n<h5>Data et leader d&#8217;opinion : un facteur d\u00e9terminant pour l&#8217;innovation pour l&#8217;industrie pharmaceutique <\/h5>\n<\/div>\n<div class=\"resource-card__media\"><img decoding=\"async\" src=\"https:\/\/www.veeva.com\/eu\/wp-content\/uploads\/2026\/02\/news-tile-jdn-300x150@2x.png\"><\/div>\n<p><\/a><\/p>\n<p><a class=\"resource-card\" href=\"https:\/\/www.veeva.com\/eu\/fr\/ressources\/iqvia-et-veeva-annoncent-des-partenariats-cliniques-et-commerciaux-a-long-terme-ainsi-que-la-resolution-de-leurs-litiges\/\" target=\"_self\" rel=\"noopener\"><\/p>\n<div class=\"resource-card__text\">\n<h5>IQVIA et Veeva annoncent des partenariats cliniques et commerciaux \u00e0 long terme ainsi que la r\u00e9solution de leurs litiges <\/h5>\n<\/div>\n<div class=\"resource-card__media\"><img decoding=\"async\" src=\"https:\/\/www.veeva.com\/eu\/wp-content\/uploads\/2026\/02\/news-tile-iqvia-veeva-300x150@2x.png\"><\/div>\n<p><\/a><\/p>\n<p><a class=\"resource-card\" href=\"https:\/\/buzz-esante.fr\/veeva-france-connect-2025-linnovation-au-service-de-lefficacite-operationnelle\/\" target=\"_blank\" rel=\"noopener\"><\/p>\n<div class=\"resource-card__text\">\n<h5>Veeva France Connect 2025 : l\u2019innovation au service de l\u2019efficacit\u00e9 op\u00e9rationnelle  <\/h5>\n<\/div>\n<div class=\"resource-card__media\"><img decoding=\"async\" src=\"https:\/\/www.veeva.com\/eu\/wp-content\/uploads\/2026\/02\/news-tile-buzz-esante-300x150@2x.png\"><\/div>\n<p><\/a><\/p>\n<p><a class=\"resource-card\" href=\"https:\/\/www.veeva.com\/eu\/fr\/ressources\/astellas-choisit-la-plateforme-veeva-pour-son-crm-a-lechelle-mondiale\/\"><\/p>\n<div class=\"resource-card__text\">\n<h5>Astellas choisit la plateforme Veeva pour son CRM \u00e0 l\u2019\u00e9chelle mondiale <\/h5>\n<\/div>\n<div class=\"resource-card__media\"><img decoding=\"async\" src=\"https:\/\/www.veeva.com\/eu\/wp-content\/uploads\/2026\/02\/news-tile-astellas-vault-CRM-300x150@2x.png\"><\/div>\n<p><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Data et leader d&#8217;opinion : un facteur d\u00e9terminant pour l&#8217;innovation pour l&#8217;industrie pharmaceutique IQVIA et Veeva annoncent des partenariats cliniques et commerciaux \u00e0 long terme ainsi que la r\u00e9solution de leurs litiges Veeva France Connect 2025 : l\u2019innovation au service de l\u2019efficacit\u00e9 op\u00e9rationnelle Astellas choisit la plateforme Veeva pour son CRM \u00e0 l\u2019\u00e9chelle mondiale<\/p>\n","protected":false},"author":223,"featured_media":9794,"parent":52562,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"archive-press-releases-french.php","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"coauthors":[],"class_list":["post-65586","page","type-page","status-publish","has-post-thumbnail","hentry","page-canonical-unique"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Data et leader d&#039;opinion : un facteur d\u00e9terminant pour l&#039;innovation pour l&#039;industrie pharmaceutique IQVIA et Veeva annoncent des partenariats cliniques et commerciaux \u00e0 long terme ainsi que la r\u00e9solution de leurs litiges Veeva France Connect 2025 : l\u2019innovation au service de l\u2019efficacit\u00e9 op\u00e9rationnelle Astellas choisit la plateforme Veeva pour son CRM \u00e0 l\u2019\u00e9chelle mondiale\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.veeva.com\/eu\/fr\/news\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Veeva Systems Europe\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Communiqu\u00e9s de presse | Veeva Systems Europe\" \/>\n\t\t<meta property=\"og:description\" content=\"Data et leader d&#039;opinion : un facteur d\u00e9terminant pour l&#039;innovation pour l&#039;industrie pharmaceutique IQVIA et Veeva annoncent des partenariats cliniques et commerciaux \u00e0 long terme ainsi que la r\u00e9solution de leurs litiges Veeva France Connect 2025 : l\u2019innovation au service de l\u2019efficacit\u00e9 op\u00e9rationnelle Astellas choisit la plateforme Veeva pour son CRM \u00e0 l\u2019\u00e9chelle mondiale\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.veeva.com\/eu\/fr\/news\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.veeva.com\/eu\/wp-content\/uploads\/2026\/08\/web-default-featured-image-1200x630-2@2x.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.veeva.com\/eu\/wp-content\/uploads\/2026\/08\/web-default-featured-image-1200x630-2@2x.jpg\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2022-07-19T10:29:09+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-02-13T11:56:33+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Communiqu\u00e9s de presse | Veeva Systems Europe\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Data et leader d&#039;opinion : un facteur d\u00e9terminant pour l&#039;innovation pour l&#039;industrie pharmaceutique IQVIA et Veeva annoncent des partenariats cliniques et commerciaux \u00e0 long terme ainsi que la r\u00e9solution de leurs litiges Veeva France Connect 2025 : l\u2019innovation au service de l\u2019efficacit\u00e9 op\u00e9rationnelle Astellas choisit la plateforme Veeva pour son CRM \u00e0 l\u2019\u00e9chelle mondiale\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.veeva.com\/eu\/wp-content\/uploads\/2026\/08\/web-default-featured-image-1200x630-2@2x.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/fr\\\/news\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.veeva.com\\\/eu\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/fr\\\/#listItem\",\"name\":\"La Fondation pour l&#8217;Excellence Digitale\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/fr\\\/#listItem\",\"position\":2,\"name\":\"La Fondation pour l&#8217;Excellence Digitale\",\"item\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/fr\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/fr\\\/news\\\/#listItem\",\"name\":\"Communiqu\\u00e9s de presse\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/fr\\\/news\\\/#listItem\",\"position\":3,\"name\":\"Communiqu\\u00e9s de presse\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/fr\\\/#listItem\",\"name\":\"La Fondation pour l&#8217;Excellence Digitale\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/#organization\",\"name\":\"Veeva Systems Europe\",\"description\":\"EU Site\",\"url\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/fr\\\/news\\\/#webpage\",\"url\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/fr\\\/news\\\/\",\"name\":\"Communiqu\\u00e9s de presse | Veeva Systems Europe\",\"description\":\"Data et leader d'opinion : un facteur d\\u00e9terminant pour l'innovation pour l'industrie pharmaceutique IQVIA et Veeva annoncent des partenariats cliniques et commerciaux \\u00e0 long terme ainsi que la r\\u00e9solution de leurs litiges Veeva France Connect 2025 : l\\u2019innovation au service de l\\u2019efficacit\\u00e9 op\\u00e9rationnelle Astellas choisit la plateforme Veeva pour son CRM \\u00e0 l\\u2019\\u00e9chelle mondiale\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/fr\\\/news\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/news_hero-banner_background.jpg\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/fr\\\/news\\\/#mainImage\",\"width\":1280,\"height\":536},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/fr\\\/news\\\/#mainImage\"},\"datePublished\":\"2022-07-19T12:29:09+02:00\",\"dateModified\":\"2026-02-13T12:56:33+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/#website\",\"url\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/\",\"name\":\"Veeva Systems Europe\",\"description\":\"EU Site\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Communiqu\u00e9s de presse | Veeva Systems Europe<\/title>\n\n","aioseo_head_json":{"title":"Communiqu\u00e9s de presse | Veeva Systems Europe","description":"Data et leader d'opinion : un facteur d\u00e9terminant pour l'innovation pour l'industrie pharmaceutique IQVIA et Veeva annoncent des partenariats cliniques et commerciaux \u00e0 long terme ainsi que la r\u00e9solution de leurs litiges Veeva France Connect 2025 : l\u2019innovation au service de l\u2019efficacit\u00e9 op\u00e9rationnelle Astellas choisit la plateforme Veeva pour son CRM \u00e0 l\u2019\u00e9chelle mondiale","canonical_url":"https:\/\/www.veeva.com\/eu\/fr\/news\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.veeva.com\/eu\/fr\/news\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.veeva.com\/eu#listItem","position":1,"name":"Home","item":"https:\/\/www.veeva.com\/eu","nextItem":{"@type":"ListItem","@id":"https:\/\/www.veeva.com\/eu\/fr\/#listItem","name":"La Fondation pour l&#8217;Excellence Digitale"}},{"@type":"ListItem","@id":"https:\/\/www.veeva.com\/eu\/fr\/#listItem","position":2,"name":"La Fondation pour l&#8217;Excellence Digitale","item":"https:\/\/www.veeva.com\/eu\/fr\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.veeva.com\/eu\/fr\/news\/#listItem","name":"Communiqu\u00e9s de presse"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.veeva.com\/eu#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.veeva.com\/eu\/fr\/news\/#listItem","position":3,"name":"Communiqu\u00e9s de presse","previousItem":{"@type":"ListItem","@id":"https:\/\/www.veeva.com\/eu\/fr\/#listItem","name":"La Fondation pour l&#8217;Excellence Digitale"}}]},{"@type":"Organization","@id":"https:\/\/www.veeva.com\/eu\/#organization","name":"Veeva Systems Europe","description":"EU Site","url":"https:\/\/www.veeva.com\/eu\/"},{"@type":"WebPage","@id":"https:\/\/www.veeva.com\/eu\/fr\/news\/#webpage","url":"https:\/\/www.veeva.com\/eu\/fr\/news\/","name":"Communiqu\u00e9s de presse | Veeva Systems Europe","description":"Data et leader d'opinion : un facteur d\u00e9terminant pour l'innovation pour l'industrie pharmaceutique IQVIA et Veeva annoncent des partenariats cliniques et commerciaux \u00e0 long terme ainsi que la r\u00e9solution de leurs litiges Veeva France Connect 2025 : l\u2019innovation au service de l\u2019efficacit\u00e9 op\u00e9rationnelle Astellas choisit la plateforme Veeva pour son CRM \u00e0 l\u2019\u00e9chelle mondiale","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/www.veeva.com\/eu\/#website"},"breadcrumb":{"@id":"https:\/\/www.veeva.com\/eu\/fr\/news\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/www.veeva.com\/eu\/wp-content\/uploads\/2015\/07\/news_hero-banner_background.jpg","@id":"https:\/\/www.veeva.com\/eu\/fr\/news\/#mainImage","width":1280,"height":536},"primaryImageOfPage":{"@id":"https:\/\/www.veeva.com\/eu\/fr\/news\/#mainImage"},"datePublished":"2022-07-19T12:29:09+02:00","dateModified":"2026-02-13T12:56:33+01:00"},{"@type":"WebSite","@id":"https:\/\/www.veeva.com\/eu\/#website","url":"https:\/\/www.veeva.com\/eu\/","name":"Veeva Systems Europe","description":"EU Site","inLanguage":"en-US","publisher":{"@id":"https:\/\/www.veeva.com\/eu\/#organization"}}]},"og:locale":"en_US","og:site_name":"Veeva Systems Europe","og:type":"article","og:title":"Communiqu\u00e9s de presse | Veeva Systems Europe","og:description":"Data et leader d'opinion : un facteur d\u00e9terminant pour l'innovation pour l'industrie pharmaceutique IQVIA et Veeva annoncent des partenariats cliniques et commerciaux \u00e0 long terme ainsi que la r\u00e9solution de leurs litiges Veeva France Connect 2025 : l\u2019innovation au service de l\u2019efficacit\u00e9 op\u00e9rationnelle Astellas choisit la plateforme Veeva pour son CRM \u00e0 l\u2019\u00e9chelle mondiale","og:url":"https:\/\/www.veeva.com\/eu\/fr\/news\/","og:image":"https:\/\/www.veeva.com\/eu\/wp-content\/uploads\/2026\/08\/web-default-featured-image-1200x630-2@2x.jpg","og:image:secure_url":"https:\/\/www.veeva.com\/eu\/wp-content\/uploads\/2026\/08\/web-default-featured-image-1200x630-2@2x.jpg","article:published_time":"2022-07-19T10:29:09+00:00","article:modified_time":"2026-02-13T11:56:33+00:00","twitter:card":"summary","twitter:title":"Communiqu\u00e9s de presse | Veeva Systems Europe","twitter:description":"Data et leader d'opinion : un facteur d\u00e9terminant pour l'innovation pour l'industrie pharmaceutique IQVIA et Veeva annoncent des partenariats cliniques et commerciaux \u00e0 long terme ainsi que la r\u00e9solution de leurs litiges Veeva France Connect 2025 : l\u2019innovation au service de l\u2019efficacit\u00e9 op\u00e9rationnelle Astellas choisit la plateforme Veeva pour son CRM \u00e0 l\u2019\u00e9chelle mondiale","twitter:image":"https:\/\/www.veeva.com\/eu\/wp-content\/uploads\/2026\/08\/web-default-featured-image-1200x630-2@2x.jpg"},"aioseo_meta_data":{"post_id":"65586","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"article","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"summary","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":{"id":"#aioseo-web-page-64119904ae46b","slug":"web-page","graphName":"WebPage","label":"Web Page","properties":{"type":"WebPage","name":"","description":""}}},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"limit_modified_date":false,"open_ai":"{\"title\":{\"suggestions\":[],\"usage\":0},\"description\":{\"suggestions\":[],\"usage\":0}}","created":"2022-07-19 10:23:21","updated":"2026-08-20 20:20:47","focus_keyword":null,"additional_keywords":null,"truseo_locale":null,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":"2026-08-20 20:20:47"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.veeva.com\/eu\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.veeva.com\/eu\/fr\/\" title=\"La Fondation pour l\u2019Excellence Digitale\">La Fondation pour l\u2019Excellence Digitale<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tCommuniqu\u00e9s de presse\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.veeva.com\/eu"},{"label":"La Fondation pour l&#8217;Excellence Digitale","link":"https:\/\/www.veeva.com\/eu\/fr\/"},{"label":"Communiqu\u00e9s de presse","link":"https:\/\/www.veeva.com\/eu\/fr\/news\/"}],"_links":{"self":[{"href":"https:\/\/www.veeva.com\/eu\/wp-json\/wp\/v2\/pages\/65586","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.veeva.com\/eu\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.veeva.com\/eu\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.veeva.com\/eu\/wp-json\/wp\/v2\/users\/223"}],"replies":[{"embeddable":true,"href":"https:\/\/www.veeva.com\/eu\/wp-json\/wp\/v2\/comments?post=65586"}],"version-history":[{"count":7,"href":"https:\/\/www.veeva.com\/eu\/wp-json\/wp\/v2\/pages\/65586\/revisions"}],"predecessor-version":[{"id":94060,"href":"https:\/\/www.veeva.com\/eu\/wp-json\/wp\/v2\/pages\/65586\/revisions\/94060"}],"up":[{"embeddable":true,"href":"https:\/\/www.veeva.com\/eu\/wp-json\/wp\/v2\/pages\/52562"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.veeva.com\/eu\/wp-json\/wp\/v2\/media\/9794"}],"wp:attachment":[{"href":"https:\/\/www.veeva.com\/eu\/wp-json\/wp\/v2\/media?parent=65586"}],"wp:term":[{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.veeva.com\/eu\/wp-json\/wp\/v2\/coauthors?post=65586"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}