{"id":63518,"date":"2022-03-29T13:03:49","date_gmt":"2022-03-29T11:03:49","guid":{"rendered":"http:\/\/www.veeva.com\/eu\/?post_type=resources_de&#038;p=63518"},"modified":"2025-10-20T15:05:04","modified_gmt":"2025-10-20T13:05:04","slug":"boehringer-ingelheim-setzt-weltweit-auf-veeva-development-cloud-um-patienten-schneller-innovative-therapien-zu-ermoglichen","status":"publish","type":"resources_de","link":"https:\/\/www.veeva.com\/eu\/de\/ressourcen\/boehringer-ingelheim-setzt-weltweit-auf-veeva-development-cloud-um-patienten-schneller-innovative-therapien-zu-ermoglichen\/","title":{"rendered":"Boehringer Ingelheim setzt weltweit auf <br class=\"hidden-xs\"> Veeva Development Cloud,  um Patienten schneller innovative Therapien zu erm\u00f6glichen"},"content":{"rendered":"<p align=\"center\"><em>Auf Basis der Veeva Development Cloud will Boehringer Ingelheim eine vernetzte Technologielandschaft f\u00fcr agiles Zusammenarbeiten schaffen, um die Entwicklung neuer Medikamente zu beschleunigen <\/em><\/p>\n<p align=\"center\"><em>Die Transformation konzentriert sich darauf, Komplexit\u00e4t zu reduzieren und eine innovative, digitale Kultur zu etablieren. Ziel ist es, Bereiche mit ungedecktem medizinischem Bedarf besser zu verstehen und zukunftsweisende Therapien zu entwickeln<\/em><\/p>\n<p><strong>INGELHEIM, Germany und PLEASANTON, CA, USA \u2013 29. M\u00e4rz 2022 &#8211; <\/strong> <a href=\"https:\/\/www.boehringer-ingelheim.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">Boehringer Ingelheim<\/a> und <a href=\"\/eu\/\" target=\"_blank\" rel=\"noopener noreferrer\">Veeva Systems<\/a> (NYSE: VEEV) haben heute bekannt gegeben, dass sich Boehringer Ingelheim f\u00fcr die <a href=\"\/eu\/products\/development-cloud\/\" target=\"_blank\" rel=\"noopener noreferrer\">Veeva Development Cloud<\/a> entschieden hat, um durchg\u00e4ngige Prozesse (End-to-End) und einen nahtlosen Informationsaustausch zu f\u00f6rdern, mit dem Ziel, innovative Therapien schneller bereitstellen zu k\u00f6nnen. Boehringer Ingelheim, ein f\u00fchrendes forschungsorientiertes biopharmazeutisches Unternehmen, arbeitet an bahnbrechenden Therapien, die das Leben von Mensch und Tier verbessern, und schafft Werte durch Innovationen in Bereichen mit hohem ungedecktem medizinischen Bedarf. Durch die Zusammenf\u00fchrung von Daten und Prozessen aus der klinischen Forschung, den regulatorischen Bereichen und der Qualit\u00e4tssicherung auf einer einzigen Cloud-Plattform schafft Boehringer Ingelheim eine vernetzte Technologielandschaft f\u00fcr effizientes Zusammenarbeiten. Ziel ist, die Entwicklung neuer Medikamente zu beschleunigen. <\/p>\n<p>Die Transformation ist Teil der Medicine Excellence-Initiative von Boehringer Ingelheim.  Das Unternehmen setzt Technologien ein, um eine zentrale medizinische Plattform zu schaffen (\u201eOne Medicine Platform\u201c), auf der s\u00e4mtliche Entwicklungsprozesse und Daten vereint sind. Die Technologie von Veeva wird dazu beitragen, diese Vision Wirklichkeit werden zu lassen. Mit der Veeva Development Cloud wird Boehringer Ingelheim seine IT-Infrastruktur weiter rationalisieren und eine konsistentere Benutzererfahrung bieten, die den Zugriff auf Informationen und die funktions\u00fcbergreifende Zusammenarbeit erleichtert. <\/p>\n<p>\u201eWir glauben an die F\u00f6rderung der Gesundheit durch Partnerschaften und freuen uns darauf, diese Reise anzutreten und unsere F\u00e4higkeit zu st\u00e4rken, das Leben der Patienten positiv zu beeinflussen\u201c, sagte Uli Br\u00f6dl, Senior Vice President, Global Clinical Development and Operations bei Boehringer Ingelheim. \u201eVeeva Development Cloud wird es funktions\u00fcbergreifenden Teams erm\u00f6glichen, intensiver zusammenzuarbeiten, gemeinsam Daten und Erkenntnisse zu nutzen und somit ihre Arbeitsweise zu verbessern.\u201c<\/p>\n<p>Im Rahmen der Veeva Development Cloud wird Boehringer Ingelheim die klinische Entwicklung mit Hilfe von <a href=\"\/eu\/products\/clinical-data-management\/\" target=\"_blank\" rel=\"noopener noreferrer\">Vault CDMS<\/a>, <a href=\"\/eu\/products\/veeva-ctms\/\" target=\"_blank\" rel=\"noopener noreferrer\">Vault CTMS<\/a>, <a href=\"\/eu\/products\/veeva-etmf\/\" target=\"_blank\" rel=\"noopener noreferrer\">Vault eTMF<\/a>, <a href=\"\/eu\/products\/veeva-ctms\/\" target=\"_blank\" rel=\"noopener noreferrer\">Vault Study Start-up<\/a> und <a href=\"\/eu\/products\/veeva-payments\/\" target=\"_blank\" rel=\"noopener noreferrer\">Vault Payments<\/a> beschleunigen, regulatorische Aktivit\u00e4ten mit <a href=\"\/eu\/products\/veeva-registrations\/\" target=\"_blank\" rel=\"noopener noreferrer\">Vault Registrations<\/a>, <a href=\"\/eu\/products\/veeva-submissions\/\" target=\"_blank\" rel=\"noopener noreferrer\">Vault Submissions<\/a>, <a href=\"\/eu\/products\/veeva-submissions-publishing\/\" target=\"_blank\" rel=\"noopener noreferrer\">Vault Submissions Publishing<\/a> und <a href=\"\/eu\/products\/veeva-submissions-archive\/\" target=\"_blank\" rel=\"noopener noreferrer\">Vault Submissions Archive<\/a> straffen und  Qualit\u00e4tsprozesse mit <a href=\"\/eu\/products\/veeva-qms\/\" target=\"_blank\" rel=\"noopener noreferrer\">Vault QMS<\/a> und <a href=\"\/eu\/products\/veeva-qualitydocs\/\" target=\"_blank\" rel=\"noopener noreferrer\">Vault QualityDocs<\/a> vereinfachen. Das Unternehmen wird seine Reise mit der Veeva Digital Trials Platform beginnen und dabei  <a href=\"\/eu\/products\/veeva-site-connect\/\" target=\"_blank\" rel=\"noopener noreferrer\">Veeva Site Connect<\/a> nutzen, um den Informationsfluss mit Partnerforschungseinrichtungen zu automatisieren. <\/p>\n<p>\u201eIn dem wir Veevas Datenmanagement- und Betriebsanwendungen f\u00fcr die klinischen Forschung im Tandem mit den L\u00f6sungen f\u00fcr die Bereiche Regulierung und Qualit\u00e4tssicherung nutzen, werden wir in der Lage sein, die Barrieren zwischen unterschiedlichen Funktionen zu \u00f6ffnen und die Zusammenarbeit kontinuierlich verbessern,\u201c, so Thomas Reith, Senior Vice President, Head of IT Research, Development and Medicine bei Boehringer Ingelheim. \u201eMit vereinheitlichten Daten und Prozessen k\u00f6nnen wir die Komplexit\u00e4t reduzieren und eine innovative, digitale Kultur entwickeln, um medizinische Fragen besser zu verstehen und zu l\u00f6sen.\u201c<\/p>\n<p>\u201eBoehringer Ingelheim und Veeva sind seit mehr als zehn Jahren \u00fcber eine hervorragende Partnerschaft miteinander verbunden, die im vertrieblichen Bereich begann. Innovationsfreude, ein hohes Ma\u00df an Kundenorientierung und die Pr\u00e4ferenz, langfristig zu planen \u2013 das verbindet die Teams beider Unternehmen gleicherma\u00dfen \u201c, so Peter Gassner, Gr\u00fcnder und CEO von Veeva. \u201eWir freuen uns und f\u00fchlen uns geehrt, jetzt in diese n\u00e4chste Phase unserer Partnerschaft mit Boehringer Ingelheim einzutreten.\u201c<\/p>\n<p>\u201eBoehringer Ingelheim gestaltet die Zukunft des Gesundheitswesens, indem es neue Wege einschl\u00e4gt, um alte Herausforderungen zu l\u00f6sen\u201c, so Rik Van Mol, Senior Vice President, Veeva Development Cloud. \u201eWir sind stolz darauf, ein zuverl\u00e4ssiger Partner zu sein, der Boehringer Ingelheim dabei unterst\u00fctzt, die Forschung und Entwicklung voranzutreiben, gleichzeitig seine Mitarbeiter mit Daten f\u00fcr ihre Gesch\u00e4ftsprozesse zu unterst\u00fctzen und eine verbesserte Benutzererfahrung zu erreichen.\u201c<\/p>\n<p class=\"mb-10\"><strong>Weitere Informationen<\/strong><br \/>\nMehr \u00fcber Veeva Development Cloud finden Sie unter: <a href=\"\/eu\/products\/development-cloud\/\" target=\"_blank\" rel=\"noopener noreferrer\">veeva.com\/eu\/DevelopmentCloud<\/a> <br \/>\nVerbinden Sie sich mit Veeva auf LinkedIn: <a href=\"https:\/\/www.linkedin.com\/company\/veeva-systems\" target=\"_blank\" rel=\"noopener noreferrer\">linkedin.com\/company\/veeva-systems<\/a><br \/>\nFolgen Sie @veeva_eu auf Twitter: <a href=\"https:\/\/twitter.com\/veeva_eu\" target=\"_blank\" rel=\"noopener noreferrer\">twitter.com\/veeva_eu <\/a><\/br><\/p>\n<p class=\"mb-10\"><strong>\u00dcber Boehringer Ingelheim<\/strong><br \/>\nBoehringer Ingelheim arbeitet an bahnbrechenden Therapien, die das Leben von Mensch und Tier verbessern. Als f\u00fchrendes forschungsgetriebenes biopharmazeutisches Unternehmen schafft das Unternehmen Werte durch Innovationen in Bereichen mit hohem ungedeckten medizinischen Bedarf. Seit seiner Gr\u00fcndung im Jahr 1885 ist Boehringer Ingelheim in Familienbesitz und verfolgt eine langfristige Perspektive. Rund 52.000 Mitarbeitende bedienen mehr als 130 M\u00e4rkte in den drei Gesch\u00e4ftsbereichen Humanpharma, Tiergesundheit und Biopharmazeutische Auftragsproduktion.<\/p>\n<p>Weitere Informationen \u00fcber Boehringer Ingelheim finden Sie unter <a href=\"https:\/\/www.boehringer-ingelheim.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">www.boehringer-ingelheim.com<\/a>.<\/p>\n<p class=\"mb-10\"><strong>Hinweis auf die Zielgruppen von Boehringer Ingelheim <\/strong><br \/>\nDiese Pressemitteilung wird von unserem Hauptsitz in Ingelheim, Deutschland, herausgegeben und soll Informationen \u00fcber unser weltweites Gesch\u00e4ft liefern. Bitte beachten Sie, dass die Informationen \u00fcber den Zulassungsstatus und die Kennzeichnung der zugelassenen Produkte von Land zu Land unterschiedlich sein k\u00f6nnen und dass in den L\u00e4ndern, in denen wir t\u00e4tig sind, m\u00f6glicherweise eine l\u00e4nderspezifische Pressemitteilung zu diesem Thema herausgegeben wurde.<\/p>\n<p class=\"mb-10\"><strong>\u00dcber Veeva Systems<\/strong><br \/>\nVeeva ist der f\u00fchrende Anbieter von Cloud-basierten Softwarel\u00f6sungen f\u00fcr die globale Life-Science-Branche. Veeva hat sich der Innovation, h\u00f6chster Produktqualit\u00e4t und dem Kundenerfolg verpflichtet. Das Unternehmen betreut mehr als 1000 Kunden, von den weltweit gr\u00f6\u00dften Pharmakonzernen bis hin zu neu gegr\u00fcndeten Biotechfirmen. Als gemeinn\u00fctzige Gesellschaft ist Veeva bestrebt, die Interessen aller Beteiligten, einschlie\u00dflich der Kunden, Mitarbeiter, Aktion\u00e4re und der von ihr bedienten Branchen, in Einklang zu bringen. Weitere Informationen finden Sie unter <a href=\"\/eu\/de\/\">veeva.com\/eu\/de<\/a>.<\/p>\n<p class=\"mb-10\"><strong>Zukunftsgerichtete Aussagen<\/strong><br \/>\nDiese Mitteilung enth\u00e4lt zukunftsgerichtete Aussagen \u00fcber die Produkte und Dienstleistungen von Veeva und die erwarteten Ergebnisse oder Vorteile aus der Nutzung unserer Produkte und Dienstleistungen. Solche Aussagen beruhen auf unseren derzeitigen Erwartungen. Die tats\u00e4chlichen Ergebnisse k\u00f6nnen erheblich von den in dieser Mitteilung gemachten Angaben abweichen, und wir sind nicht verpflichtet, solche Aussagen zu aktualisieren. Es gibt zahlreiche Risiken, die sich negativ auf unsere Ergebnisse auswirken k\u00f6nnen, einschlie\u00dflich der Risiken und Ungewissheiten, die in unserem Formular 10-Q f\u00fcr den Zeitraum bis zum 31. Oktober 2021 aufgef\u00fchrt sind, das Sie <a href=\"https:\/\/www.sec.gov\/ix?doc=\/Archives\/edgar\/data\/1393052\/000139305221000040\/veev-20211031.htm\" target=\"_blank\" rel=\"noopener noreferrer\">hier<\/a> finden k\u00f6nnen (eine Zusammenfassung der Risiken, die sich auf unser Gesch\u00e4ft auswirken k\u00f6nnen, finden Sie auf Seite 39), sowie in unseren nachfolgenden SEC-Einreichungen, die Sie unter <a href=\"https:\/\/www.sec.gov\/\" target=\"_blank\" rel=\"noopener noreferrer\">sec.gov<\/a> einsehen k\u00f6nnen. <\/p>\n<p>###<\/p>\n<p><strong>Kontakt:<\/strong><\/p>\n<p>Deivis Mercado <br \/>\nVeeva Systems <br \/>\n925-226-8821 <br \/>\n<a href=\"mailto:deivis.mercado@veeva.com\">deivis.mercado@veeva.com<\/a><\/p>\n<p>Tereza Urbankova<br \/>\nBoehringer Ingelheim<br \/>\n+49 6132 77184817<br \/>\n<a href=\"mailto:press@boehringer-ingelheim.com\">press@boehringer-ingelheim.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Boehringer Ingelheim will eine vernetzte Technologielandschaft f\u00fcr eine agile Zusammenarbeit schaffen, die die Entwicklung neuer Medikamente beschleunigen kann.<\/p>\n","protected":false},"featured_media":63511,"parent":0,"template":"","class_list":["post-63518","resources_de","type-resources_de","status-publish","has-post-thumbnail","hentry","resources-de-canonical-unique","resource-social-hide-social-icons","resource-de-type-pressemitteilungen","resource-de-area-area-development-cloud","resource-de-product-product-development-cloud"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Boehringer Ingelheim will eine vernetzte Technologielandschaft f\u00fcr eine agile Zusammenarbeit schaffen, die die Entwicklung neuer Medikamente beschleunigen kann.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.veeva.com\/eu\/de\/ressourcen\/boehringer-ingelheim-setzt-weltweit-auf-veeva-development-cloud-um-patienten-schneller-innovative-therapien-zu-ermoglichen\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Veeva Systems Europe\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Boehringer Ingelheim setzt weltweit auf Veeva Development Cloud, um Patienten schneller innovative Therapien zu erm\u00f6glichen | Veeva Systems Europe\" \/>\n\t\t<meta property=\"og:description\" content=\"Boehringer Ingelheim will eine vernetzte Technologielandschaft f\u00fcr eine agile Zusammenarbeit schaffen, die die Entwicklung neuer Medikamente beschleunigen kann.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.veeva.com\/eu\/de\/ressourcen\/boehringer-ingelheim-setzt-weltweit-auf-veeva-development-cloud-um-patienten-schneller-innovative-therapien-zu-ermoglichen\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.veeva.com\/eu\/wp-content\/uploads\/2022\/03\/BI-adopts-Dev-Cloud-Social-Graphics_LinkedIn_V3_FB-LinkedIn_German.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.veeva.com\/eu\/wp-content\/uploads\/2022\/03\/BI-adopts-Dev-Cloud-Social-Graphics_LinkedIn_V3_FB-LinkedIn_German.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2022-03-29T11:03:49+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-10-20T13:05:04+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Boehringer Ingelheim setzt weltweit auf Veeva Development Cloud, um Patienten schneller innovative Therapien zu erm\u00f6glichen | Veeva Systems Europe\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Boehringer Ingelheim will eine vernetzte Technologielandschaft f\u00fcr eine agile Zusammenarbeit schaffen, die die Entwicklung neuer Medikamente beschleunigen kann.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.veeva.com\/eu\/wp-content\/uploads\/2022\/03\/BI-adopts-Dev-Cloud-Social-Graphics_LinkedIn_V3_FB-LinkedIn_German.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/de\\\/ressourcen\\\/boehringer-ingelheim-setzt-weltweit-auf-veeva-development-cloud-um-patienten-schneller-innovative-therapien-zu-ermoglichen\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.veeva.com\\\/eu\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/de\\\/ressourcen\\\/#listItem\",\"name\":\"Resources - DE\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/de\\\/ressourcen\\\/#listItem\",\"position\":2,\"name\":\"Resources - DE\",\"item\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/de\\\/ressourcen\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/resources-de-canonical\\\/unique\\\/#listItem\",\"name\":\"Make Unique\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/resources-de-canonical\\\/unique\\\/#listItem\",\"position\":3,\"name\":\"Make Unique\",\"item\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/resources-de-canonical\\\/unique\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/de\\\/ressourcen\\\/boehringer-ingelheim-setzt-weltweit-auf-veeva-development-cloud-um-patienten-schneller-innovative-therapien-zu-ermoglichen\\\/#listItem\",\"name\":\"Boehringer Ingelheim setzt weltweit auf  Veeva Development Cloud,  um Patienten schneller innovative Therapien zu erm\\u00f6glichen\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/de\\\/ressourcen\\\/#listItem\",\"name\":\"Resources - DE\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/de\\\/ressourcen\\\/boehringer-ingelheim-setzt-weltweit-auf-veeva-development-cloud-um-patienten-schneller-innovative-therapien-zu-ermoglichen\\\/#listItem\",\"position\":4,\"name\":\"Boehringer Ingelheim setzt weltweit auf  Veeva Development Cloud,  um Patienten schneller innovative Therapien zu erm\\u00f6glichen\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/resources-de-canonical\\\/unique\\\/#listItem\",\"name\":\"Make Unique\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/#organization\",\"name\":\"Veeva Systems Europe\",\"description\":\"EU Site\",\"url\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/de\\\/ressourcen\\\/boehringer-ingelheim-setzt-weltweit-auf-veeva-development-cloud-um-patienten-schneller-innovative-therapien-zu-ermoglichen\\\/#webpage\",\"url\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/de\\\/ressourcen\\\/boehringer-ingelheim-setzt-weltweit-auf-veeva-development-cloud-um-patienten-schneller-innovative-therapien-zu-ermoglichen\\\/\",\"name\":\"Boehringer Ingelheim setzt weltweit auf Veeva Development Cloud, um Patienten schneller innovative Therapien zu erm\\u00f6glichen | Veeva Systems Europe\",\"description\":\"Boehringer Ingelheim will eine vernetzte Technologielandschaft f\\u00fcr eine agile Zusammenarbeit schaffen, die die Entwicklung neuer Medikamente beschleunigen kann.\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/de\\\/ressourcen\\\/boehringer-ingelheim-setzt-weltweit-auf-veeva-development-cloud-um-patienten-schneller-innovative-therapien-zu-ermoglichen\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/BI-Selects-Veeva-Dev-Cloud-Resource-Tile.png\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/de\\\/ressourcen\\\/boehringer-ingelheim-setzt-weltweit-auf-veeva-development-cloud-um-patienten-schneller-innovative-therapien-zu-ermoglichen\\\/#mainImage\",\"width\":340,\"height\":240,\"caption\":\"BI Selects Veeva Dev Cloud Resource Tile\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/de\\\/ressourcen\\\/boehringer-ingelheim-setzt-weltweit-auf-veeva-development-cloud-um-patienten-schneller-innovative-therapien-zu-ermoglichen\\\/#mainImage\"},\"datePublished\":\"2022-03-29T13:03:49+02:00\",\"dateModified\":\"2025-10-20T15:05:04+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/#website\",\"url\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/\",\"name\":\"Veeva Systems Europe\",\"description\":\"EU Site\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Boehringer Ingelheim setzt weltweit auf Veeva Development Cloud, um Patienten schneller innovative Therapien zu erm\u00f6glichen | Veeva Systems Europe<\/title>\n\n","aioseo_head_json":{"title":"Boehringer Ingelheim setzt weltweit auf Veeva Development Cloud, um Patienten schneller innovative Therapien zu erm\u00f6glichen | Veeva Systems Europe","description":"Boehringer Ingelheim will eine vernetzte Technologielandschaft f\u00fcr eine agile Zusammenarbeit schaffen, die die Entwicklung neuer Medikamente beschleunigen kann.","canonical_url":"https:\/\/www.veeva.com\/eu\/de\/ressourcen\/boehringer-ingelheim-setzt-weltweit-auf-veeva-development-cloud-um-patienten-schneller-innovative-therapien-zu-ermoglichen\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.veeva.com\/eu\/de\/ressourcen\/boehringer-ingelheim-setzt-weltweit-auf-veeva-development-cloud-um-patienten-schneller-innovative-therapien-zu-ermoglichen\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.veeva.com\/eu#listItem","position":1,"name":"Home","item":"https:\/\/www.veeva.com\/eu","nextItem":{"@type":"ListItem","@id":"https:\/\/www.veeva.com\/eu\/de\/ressourcen\/#listItem","name":"Resources - DE"}},{"@type":"ListItem","@id":"https:\/\/www.veeva.com\/eu\/de\/ressourcen\/#listItem","position":2,"name":"Resources - DE","item":"https:\/\/www.veeva.com\/eu\/de\/ressourcen\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.veeva.com\/eu\/resources-de-canonical\/unique\/#listItem","name":"Make Unique"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.veeva.com\/eu#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.veeva.com\/eu\/resources-de-canonical\/unique\/#listItem","position":3,"name":"Make Unique","item":"https:\/\/www.veeva.com\/eu\/resources-de-canonical\/unique\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.veeva.com\/eu\/de\/ressourcen\/boehringer-ingelheim-setzt-weltweit-auf-veeva-development-cloud-um-patienten-schneller-innovative-therapien-zu-ermoglichen\/#listItem","name":"Boehringer Ingelheim setzt weltweit auf  Veeva Development Cloud,  um Patienten schneller innovative Therapien zu erm\u00f6glichen"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.veeva.com\/eu\/de\/ressourcen\/#listItem","name":"Resources - DE"}},{"@type":"ListItem","@id":"https:\/\/www.veeva.com\/eu\/de\/ressourcen\/boehringer-ingelheim-setzt-weltweit-auf-veeva-development-cloud-um-patienten-schneller-innovative-therapien-zu-ermoglichen\/#listItem","position":4,"name":"Boehringer Ingelheim setzt weltweit auf  Veeva Development Cloud,  um Patienten schneller innovative Therapien zu erm\u00f6glichen","previousItem":{"@type":"ListItem","@id":"https:\/\/www.veeva.com\/eu\/resources-de-canonical\/unique\/#listItem","name":"Make Unique"}}]},{"@type":"Organization","@id":"https:\/\/www.veeva.com\/eu\/#organization","name":"Veeva Systems Europe","description":"EU Site","url":"https:\/\/www.veeva.com\/eu\/"},{"@type":"WebPage","@id":"https:\/\/www.veeva.com\/eu\/de\/ressourcen\/boehringer-ingelheim-setzt-weltweit-auf-veeva-development-cloud-um-patienten-schneller-innovative-therapien-zu-ermoglichen\/#webpage","url":"https:\/\/www.veeva.com\/eu\/de\/ressourcen\/boehringer-ingelheim-setzt-weltweit-auf-veeva-development-cloud-um-patienten-schneller-innovative-therapien-zu-ermoglichen\/","name":"Boehringer Ingelheim setzt weltweit auf Veeva Development Cloud, um Patienten schneller innovative Therapien zu erm\u00f6glichen | Veeva Systems Europe","description":"Boehringer Ingelheim will eine vernetzte Technologielandschaft f\u00fcr eine agile Zusammenarbeit schaffen, die die Entwicklung neuer Medikamente beschleunigen kann.","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/www.veeva.com\/eu\/#website"},"breadcrumb":{"@id":"https:\/\/www.veeva.com\/eu\/de\/ressourcen\/boehringer-ingelheim-setzt-weltweit-auf-veeva-development-cloud-um-patienten-schneller-innovative-therapien-zu-ermoglichen\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/www.veeva.com\/eu\/wp-content\/uploads\/2022\/03\/BI-Selects-Veeva-Dev-Cloud-Resource-Tile.png","@id":"https:\/\/www.veeva.com\/eu\/de\/ressourcen\/boehringer-ingelheim-setzt-weltweit-auf-veeva-development-cloud-um-patienten-schneller-innovative-therapien-zu-ermoglichen\/#mainImage","width":340,"height":240,"caption":"BI Selects Veeva Dev Cloud Resource Tile"},"primaryImageOfPage":{"@id":"https:\/\/www.veeva.com\/eu\/de\/ressourcen\/boehringer-ingelheim-setzt-weltweit-auf-veeva-development-cloud-um-patienten-schneller-innovative-therapien-zu-ermoglichen\/#mainImage"},"datePublished":"2022-03-29T13:03:49+02:00","dateModified":"2025-10-20T15:05:04+02:00"},{"@type":"WebSite","@id":"https:\/\/www.veeva.com\/eu\/#website","url":"https:\/\/www.veeva.com\/eu\/","name":"Veeva Systems Europe","description":"EU Site","inLanguage":"en-US","publisher":{"@id":"https:\/\/www.veeva.com\/eu\/#organization"}}]},"og:locale":"en_US","og:site_name":"Veeva Systems Europe","og:type":"article","og:title":"Boehringer Ingelheim setzt weltweit auf Veeva Development Cloud, um Patienten schneller innovative Therapien zu erm\u00f6glichen | Veeva Systems Europe","og:description":"Boehringer Ingelheim will eine vernetzte Technologielandschaft f\u00fcr eine agile Zusammenarbeit schaffen, die die Entwicklung neuer Medikamente beschleunigen kann.","og:url":"https:\/\/www.veeva.com\/eu\/de\/ressourcen\/boehringer-ingelheim-setzt-weltweit-auf-veeva-development-cloud-um-patienten-schneller-innovative-therapien-zu-ermoglichen\/","og:image":"https:\/\/www.veeva.com\/eu\/wp-content\/uploads\/2022\/03\/BI-adopts-Dev-Cloud-Social-Graphics_LinkedIn_V3_FB-LinkedIn_German.png","og:image:secure_url":"https:\/\/www.veeva.com\/eu\/wp-content\/uploads\/2022\/03\/BI-adopts-Dev-Cloud-Social-Graphics_LinkedIn_V3_FB-LinkedIn_German.png","article:published_time":"2022-03-29T11:03:49+00:00","article:modified_time":"2025-10-20T13:05:04+00:00","twitter:card":"summary_large_image","twitter:title":"Boehringer Ingelheim setzt weltweit auf Veeva Development Cloud, um Patienten schneller innovative Therapien zu erm\u00f6glichen | Veeva Systems Europe","twitter:description":"Boehringer Ingelheim will eine vernetzte Technologielandschaft f\u00fcr eine agile Zusammenarbeit schaffen, die die Entwicklung neuer Medikamente beschleunigen kann.","twitter:image":"https:\/\/www.veeva.com\/eu\/wp-content\/uploads\/2022\/03\/BI-adopts-Dev-Cloud-Social-Graphics_LinkedIn_V3_FB-LinkedIn_German.png"},"aioseo_meta_data":{"post_id":"63518","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"custom_image","og_image_url":"https:\/\/www.veeva.com\/eu\/wp-content\/uploads\/2022\/03\/BI-adopts-Dev-Cloud-Social-Graphics_LinkedIn_V3_FB-LinkedIn_German.png","og_image_width":"1200","og_image_height":"630","og_image_custom_url":"https:\/\/www.veeva.com\/eu\/wp-content\/uploads\/2022\/03\/BI-adopts-Dev-Cloud-Social-Graphics_LinkedIn_V3_FB-LinkedIn_German.png","og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"summary_large_image","twitter_image_type":"custom_image","twitter_image_url":"https:\/\/www.veeva.com\/eu\/wp-content\/uploads\/2022\/03\/BI-adopts-Dev-Cloud-Social-Graphics_LinkedIn_V3_FB-LinkedIn_German.png","twitter_image_custom_url":"https:\/\/www.veeva.com\/eu\/wp-content\/uploads\/2022\/03\/BI-adopts-Dev-Cloud-Social-Graphics_LinkedIn_V3_FB-LinkedIn_German.png","twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"limit_modified_date":false,"open_ai":"{\"title\":{\"suggestions\":[],\"usage\":0},\"description\":{\"suggestions\":[],\"usage\":0}}","created":"2022-03-29 08:46:49","updated":"2026-08-24 21:05:43","focus_keyword":null,"additional_keywords":null,"truseo_locale":null,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":"2026-08-24 21:05:43"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.veeva.com\/eu\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.veeva.com\/eu\/de\/ressourcen\/\" title=\"Resources - DE\">Resources - DE<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.veeva.com\/eu\/resources-de-canonical\/unique\/\" title=\"Make Unique\">Make Unique<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t Veeva Development Cloud,  um Patienten schneller innovative Therapien zu erm\u00f6glichen\"&gt;Boehringer Ingelheim setzt weltweit auf <br class=\"hidden-xs\"> Veeva Development Cloud,  um Patienten schneller innovative Therapien zu erm\u00f6glichen\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.veeva.com\/eu"},{"label":"Resources - DE","link":"https:\/\/www.veeva.com\/eu\/de\/ressourcen\/"},{"label":"Make Unique","link":"https:\/\/www.veeva.com\/eu\/resources-de-canonical\/unique\/"},{"label":"Boehringer Ingelheim setzt weltweit auf <br class=\"hidden-xs\"> Veeva Development Cloud,  um Patienten schneller innovative Therapien zu erm\u00f6glichen","link":"https:\/\/www.veeva.com\/eu\/de\/ressourcen\/boehringer-ingelheim-setzt-weltweit-auf-veeva-development-cloud-um-patienten-schneller-innovative-therapien-zu-ermoglichen\/"}],"_links":{"self":[{"href":"https:\/\/www.veeva.com\/eu\/wp-json\/wp\/v2\/resources_de\/63518","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.veeva.com\/eu\/wp-json\/wp\/v2\/resources_de"}],"about":[{"href":"https:\/\/www.veeva.com\/eu\/wp-json\/wp\/v2\/types\/resources_de"}],"version-history":[{"count":1,"href":"https:\/\/www.veeva.com\/eu\/wp-json\/wp\/v2\/resources_de\/63518\/revisions"}],"predecessor-version":[{"id":86268,"href":"https:\/\/www.veeva.com\/eu\/wp-json\/wp\/v2\/resources_de\/63518\/revisions\/86268"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.veeva.com\/eu\/wp-json\/wp\/v2\/media\/63511"}],"wp:attachment":[{"href":"https:\/\/www.veeva.com\/eu\/wp-json\/wp\/v2\/media?parent=63518"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}