{"id":80340,"date":"2024-11-14T15:01:08","date_gmt":"2024-11-14T14:01:08","guid":{"rendered":"https:\/\/www.veeva.com\/eu\/?post_type=resources_de&#038;p=80340"},"modified":"2025-10-21T12:13:32","modified_gmt":"2025-10-21T10:13:32","slug":"boehringer-ingelheim-setzt-auf-veeva-vault-crm","status":"publish","type":"resources_de","link":"https:\/\/www.veeva.com\/eu\/de\/ressourcen\/boehringer-ingelheim-setzt-auf-veeva-vault-crm\/","title":{"rendered":"Boehringer Ingelheim setzt auf Veeva Vault CRM"},"content":{"rendered":"<p align=\"center\"><i>F\u00fchrendes Biopharmaunternehmen entscheidet sich f\u00fcr Life-Sciences-CRM der n\u00e4chsten Generation als Fundament f\u00fcr die zuk\u00fcnftige Expansion und Produkteinf\u00fchrungen<\/i><\/p>\n<p><strong>BARCELONA, Spanien \u2014 14 Nov. 2024 \u2014 <\/strong><a href=\"\/eu\/\" target=\"_blank\" rel=\"noopener\">Veeva Systems<\/a> (NYSE: VEEV) hat heute bekannt gegeben, dass Boehringer Ingelheim als eines der Top-20-Biopharmaunternehmen weltweit zu <a href=\"\/eu\/products\/crm-suite\/\" target=\"_blank\" rel=\"noopener\">Veeva Vault CRM<\/a> wechseln wird.<\/p>\n<p>\u201eWir freuen uns darauf, bis 2030 Patientinnen und Patienten unsere innovativen Forschungsergebnisse mit bis zu 25 neuen Produkteinf\u00fchrungen weltweit zug\u00e4nglich zu machen. Veeva ist seit vielen Jahren unser globaler CRM-Standard. Wir sind bestrebt, auf unserer erfolgreichen Partnerschaft aufzubauen und die Zukunft der Life-Sciences mit der Entscheidung f\u00fcr Veeva Vault CRM mitzugestalten\u201c, sagt Uday Bose, Head of Human Pharma Global Customer Experience Excellence and Business Steering bei Boehringer Ingelheim. \u201eMit Veeva teilen wir das Ziel, herausragende Kundenerfahrungen zu bieten. Zusammen arbeiten wir weiterhin daran, die Abl\u00e4ufe unserer kundenorientierten Bereiche (Vertrieb, Marketing und medizinischer Au\u00dfendienst) zu transformieren. Dies wird dazu beitragen, dass wir Produkte schneller einf\u00fchren und hochgradig personalisierte Interaktionen erm\u00f6glichen.\u201c<\/p>\n<p>Boehringer Ingelheim plant, seine bestehenden <a href=\"\/eu\/products\/commercial-cloud\/\" target=\"_blank\" rel=\"noopener\">Veeva Commercial Cloud<\/a>-L\u00f6sungen sowie seine One Medicine- und Amplify-Plattformen, die Entwicklungsprozesse und Daten in der <a href=\"\/eu\/products\/development-cloud\/\" target=\"_blank\" rel=\"noopener\">Veeva Development Cloud<\/a> verbinden, zu erweitern.<\/p>\n<p>\u201eBoehringer Ingelheim verfolgt einen zukunftsorientierten Ansatz, um seine Technologie- und Datenlandschaft zu vereinheitlichen. Ziel ist es, Therapien zur Verbesserung der Gesundheit von Mensch und Tier schnell bereitzustellen\u201c, sagt Tom Schwenger, President und Chief Customer Officer bei Veeva. \u201eIch freue mich sehr, unsere langj\u00e4hrige Partnerschaft mit Boehringer Ingelheim durch den Wechsel des Unternehmens zu Veeva Vault CRM weiter zu vertiefen.\u201c<\/p>\n<p>Boehringer Ingelheim wird an der Er\u00f6ffnungs-Keynote des <a href=\"\/eu\/events\/commercial-summit-europe\/overview\/\" target=\"_blank\" rel=\"noopener\">Veeva Commercial Summit Europe<\/a> teilnehmen und erl\u00e4utern, welche Rolle Vault CRM als Schl\u00fcsselfaktor f\u00fcr die zuk\u00fcnftige kommerzielle Agilit\u00e4t, Innovation und Differenzierung spielt.<\/p>\n<p><strong>Weitere Informationen<\/strong><br \/>\nMehr Informationen \u00fcber Veeva Vault CRM finden Sie hier: <a href=\"\/eu\/products\/crm-suite\/\" target=\"_blank\" rel=\"noopener\">veeva.com\/eu\/VaultCRM<\/a><\/p>\n<p><strong>\u00dcber Veeva Systems <\/strong><br \/>\nVeeva ist der weltweit f\u00fchrende Anbieter von Cloud-Software f\u00fcr die Life-Science-Branche. Veeva hat sich der Innovation, der Produktqualit\u00e4t und dem Kundenerfolg verschrieben und bedient mehr als 1.000 Kunden, von den weltweit gr\u00f6\u00dften Pharmaunternehmen bis hin zu aufstrebenden Biotechs. Als <a href=\"\/pbc\/\" target=\"_blank\" rel=\"noopener noreferrer\">Public Benefit Corporation<\/a> ist Veeva bestrebt, die Interessen aller Beteiligten, einschlie\u00dflich der Kunden, Mitarbeiter, Aktion\u00e4re und der Branchen, f\u00fcr die das Unternehmen t\u00e4tig ist, in Einklang zu bringen. F\u00fcr weitere Informationen besuchen Sie <a href=\"\/eu\/de\/\">veeva.com\/eu\/de<\/a>. <\/p>\n<p><strong>Zukunftsgerichtete Aussagen von Veeva <\/strong><br \/>\nDiese Mitteilung enth\u00e4lt zukunftsgerichtete Aussagen \u00fcber die Produkte und Dienstleistungen von Veeva und die erwarteten Ergebnisse oder Vorteile aus der Nutzung unserer Produkte und Dienstleistungen. Diese Aussagen beruhen auf unseren derzeitigen Erwartungen. Die tats\u00e4chlichen Ergebnisse k\u00f6nnen erheblich von den in dieser Mitteilung gemachten Angaben abweichen, und wir sind nicht verpflichtet, solche Aussagen zu aktualisieren. Es gibt zahlreiche Risiken, die sich negativ auf unsere Ergebnisse auswirken k\u00f6nnen, einschlie\u00dflich der Risiken und Ungewissheiten, die in unserem Formular 10-Q f\u00fcr den am 31. Juli 2024 beendeten Zeitraum, das Sie <a href=\"https:\/\/www.sec.gov\/ix?doc=\/Archives\/edgar\/data\/1393052\/000139305224000062\/veev-20240731.htm\" target=\"_blank\" rel=\"noopener\">hier<\/a> finden (eine Zusammenfassung der Risiken, die sich auf unser Gesch\u00e4ft auswirken k\u00f6nnen, finden Sie auf den Seiten 36 und 37), und in unseren nachfolgenden SEC-Einreichungen, die Sie unter <a href=\"https:\/\/www.sec.gov\/\" target=\"_blank\" rel=\"noopener\">sec.gov<\/a> finden. <\/p>\n<p class=\"text-center\">###<\/p>\n<p>\n<strong>Kontakt:<\/strong><br \/>\nMeera Lakhani-Patel<br \/>\nVeeva Systems<br \/>\n+44-790-430-0698<br \/>\n<a href=\"mailto:meera.lakhani-patel@veeva.com\">meera.lakhani-patel@veeva.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>F\u00fchrendes Biopharmaunternehmen entscheidet sich f\u00fcr Life-Sciences-CRM der n\u00e4chsten Generation als Fundament f\u00fcr die zuk\u00fcnftige Expansion und f\u00fcr Produkteinf\u00fchrungen.<\/p>\n","protected":false},"featured_media":80326,"parent":0,"template":"","class_list":["post-80340","resources_de","type-resources_de","status-publish","has-post-thumbnail","hentry","resources-de-canonical-unique","resource-html-content-yes","resource-de-type-pressemitteilungen","resource-de-area-kommerziell","resource-de-product-crm"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"F\u00fchrendes Biopharmaunternehmen entscheidet sich f\u00fcr Life-Sciences-CRM der n\u00e4chsten Generation als Fundament f\u00fcr die zuk\u00fcnftige Expansion und f\u00fcr Produkteinf\u00fchrungen.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.veeva.com\/eu\/de\/ressourcen\/boehringer-ingelheim-setzt-auf-veeva-vault-crm\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Veeva Systems Europe\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Boehringer Ingelheim setzt auf Veeva Vault CRM | Veeva Systems Europe\" \/>\n\t\t<meta property=\"og:description\" content=\"F\u00fchrendes Biopharmaunternehmen entscheidet sich f\u00fcr Life-Sciences-CRM der n\u00e4chsten Generation als Fundament f\u00fcr die zuk\u00fcnftige Expansion und f\u00fcr Produkteinf\u00fchrungen.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.veeva.com\/eu\/de\/ressourcen\/boehringer-ingelheim-setzt-auf-veeva-vault-crm\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.veeva.com\/eu\/wp-content\/uploads\/2024\/10\/resource-tile-boehringer-340x240@2x.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.veeva.com\/eu\/wp-content\/uploads\/2024\/10\/resource-tile-boehringer-340x240@2x.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"680\" \/>\n\t\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-11-14T14:01:08+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-10-21T10:13:32+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Boehringer Ingelheim setzt auf Veeva Vault CRM | Veeva Systems Europe\" \/>\n\t\t<meta name=\"twitter:description\" content=\"F\u00fchrendes Biopharmaunternehmen entscheidet sich f\u00fcr Life-Sciences-CRM der n\u00e4chsten Generation als Fundament f\u00fcr die zuk\u00fcnftige Expansion und f\u00fcr Produkteinf\u00fchrungen.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.veeva.com\/eu\/wp-content\/uploads\/2024\/10\/resource-tile-boehringer-340x240@2x.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/de\\\/ressourcen\\\/boehringer-ingelheim-setzt-auf-veeva-vault-crm\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.veeva.com\\\/eu\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/de\\\/ressourcen\\\/#listItem\",\"name\":\"Resources - DE\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/de\\\/ressourcen\\\/#listItem\",\"position\":2,\"name\":\"Resources - DE\",\"item\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/de\\\/ressourcen\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/resources-de-canonical\\\/unique\\\/#listItem\",\"name\":\"Make Unique\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/resources-de-canonical\\\/unique\\\/#listItem\",\"position\":3,\"name\":\"Make Unique\",\"item\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/resources-de-canonical\\\/unique\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/de\\\/ressourcen\\\/boehringer-ingelheim-setzt-auf-veeva-vault-crm\\\/#listItem\",\"name\":\"Boehringer Ingelheim setzt auf Veeva Vault CRM\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/de\\\/ressourcen\\\/#listItem\",\"name\":\"Resources - DE\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/de\\\/ressourcen\\\/boehringer-ingelheim-setzt-auf-veeva-vault-crm\\\/#listItem\",\"position\":4,\"name\":\"Boehringer Ingelheim setzt auf Veeva Vault CRM\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/resources-de-canonical\\\/unique\\\/#listItem\",\"name\":\"Make Unique\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/#organization\",\"name\":\"Veeva Systems Europe\",\"description\":\"EU Site\",\"url\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/de\\\/ressourcen\\\/boehringer-ingelheim-setzt-auf-veeva-vault-crm\\\/#webpage\",\"url\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/de\\\/ressourcen\\\/boehringer-ingelheim-setzt-auf-veeva-vault-crm\\\/\",\"name\":\"Boehringer Ingelheim setzt auf Veeva Vault CRM | Veeva Systems Europe\",\"description\":\"F\\u00fchrendes Biopharmaunternehmen entscheidet sich f\\u00fcr Life-Sciences-CRM der n\\u00e4chsten Generation als Fundament f\\u00fcr die zuk\\u00fcnftige Expansion und f\\u00fcr Produkteinf\\u00fchrungen.\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/de\\\/ressourcen\\\/boehringer-ingelheim-setzt-auf-veeva-vault-crm\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/resource-tile-boehringer-340x240@2x.png\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/de\\\/ressourcen\\\/boehringer-ingelheim-setzt-auf-veeva-vault-crm\\\/#mainImage\",\"width\":680,\"height\":480,\"caption\":\"resource-tile-boehringer-340x240@2x\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/de\\\/ressourcen\\\/boehringer-ingelheim-setzt-auf-veeva-vault-crm\\\/#mainImage\"},\"datePublished\":\"2024-11-14T15:01:08+01:00\",\"dateModified\":\"2025-10-21T12:13:32+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/#website\",\"url\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/\",\"name\":\"Veeva Systems Europe\",\"description\":\"EU Site\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Boehringer Ingelheim setzt auf Veeva Vault CRM | Veeva Systems Europe<\/title>\n\n","aioseo_head_json":{"title":"Boehringer Ingelheim setzt auf Veeva Vault CRM | Veeva Systems Europe","description":"F\u00fchrendes Biopharmaunternehmen entscheidet sich f\u00fcr Life-Sciences-CRM der n\u00e4chsten Generation als Fundament f\u00fcr die zuk\u00fcnftige Expansion und f\u00fcr Produkteinf\u00fchrungen.","canonical_url":"https:\/\/www.veeva.com\/eu\/de\/ressourcen\/boehringer-ingelheim-setzt-auf-veeva-vault-crm\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.veeva.com\/eu\/de\/ressourcen\/boehringer-ingelheim-setzt-auf-veeva-vault-crm\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.veeva.com\/eu#listItem","position":1,"name":"Home","item":"https:\/\/www.veeva.com\/eu","nextItem":{"@type":"ListItem","@id":"https:\/\/www.veeva.com\/eu\/de\/ressourcen\/#listItem","name":"Resources - DE"}},{"@type":"ListItem","@id":"https:\/\/www.veeva.com\/eu\/de\/ressourcen\/#listItem","position":2,"name":"Resources - DE","item":"https:\/\/www.veeva.com\/eu\/de\/ressourcen\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.veeva.com\/eu\/resources-de-canonical\/unique\/#listItem","name":"Make Unique"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.veeva.com\/eu#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.veeva.com\/eu\/resources-de-canonical\/unique\/#listItem","position":3,"name":"Make Unique","item":"https:\/\/www.veeva.com\/eu\/resources-de-canonical\/unique\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.veeva.com\/eu\/de\/ressourcen\/boehringer-ingelheim-setzt-auf-veeva-vault-crm\/#listItem","name":"Boehringer Ingelheim setzt auf Veeva Vault CRM"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.veeva.com\/eu\/de\/ressourcen\/#listItem","name":"Resources - DE"}},{"@type":"ListItem","@id":"https:\/\/www.veeva.com\/eu\/de\/ressourcen\/boehringer-ingelheim-setzt-auf-veeva-vault-crm\/#listItem","position":4,"name":"Boehringer Ingelheim setzt auf Veeva Vault CRM","previousItem":{"@type":"ListItem","@id":"https:\/\/www.veeva.com\/eu\/resources-de-canonical\/unique\/#listItem","name":"Make Unique"}}]},{"@type":"Organization","@id":"https:\/\/www.veeva.com\/eu\/#organization","name":"Veeva Systems Europe","description":"EU Site","url":"https:\/\/www.veeva.com\/eu\/"},{"@type":"WebPage","@id":"https:\/\/www.veeva.com\/eu\/de\/ressourcen\/boehringer-ingelheim-setzt-auf-veeva-vault-crm\/#webpage","url":"https:\/\/www.veeva.com\/eu\/de\/ressourcen\/boehringer-ingelheim-setzt-auf-veeva-vault-crm\/","name":"Boehringer Ingelheim setzt auf Veeva Vault CRM | Veeva Systems Europe","description":"F\u00fchrendes Biopharmaunternehmen entscheidet sich f\u00fcr Life-Sciences-CRM der n\u00e4chsten Generation als Fundament f\u00fcr die zuk\u00fcnftige Expansion und f\u00fcr Produkteinf\u00fchrungen.","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/www.veeva.com\/eu\/#website"},"breadcrumb":{"@id":"https:\/\/www.veeva.com\/eu\/de\/ressourcen\/boehringer-ingelheim-setzt-auf-veeva-vault-crm\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/www.veeva.com\/eu\/wp-content\/uploads\/2024\/10\/resource-tile-boehringer-340x240@2x.png","@id":"https:\/\/www.veeva.com\/eu\/de\/ressourcen\/boehringer-ingelheim-setzt-auf-veeva-vault-crm\/#mainImage","width":680,"height":480,"caption":"resource-tile-boehringer-340x240@2x"},"primaryImageOfPage":{"@id":"https:\/\/www.veeva.com\/eu\/de\/ressourcen\/boehringer-ingelheim-setzt-auf-veeva-vault-crm\/#mainImage"},"datePublished":"2024-11-14T15:01:08+01:00","dateModified":"2025-10-21T12:13:32+02:00"},{"@type":"WebSite","@id":"https:\/\/www.veeva.com\/eu\/#website","url":"https:\/\/www.veeva.com\/eu\/","name":"Veeva Systems Europe","description":"EU Site","inLanguage":"en-US","publisher":{"@id":"https:\/\/www.veeva.com\/eu\/#organization"}}]},"og:locale":"en_US","og:site_name":"Veeva Systems Europe","og:type":"article","og:title":"Boehringer Ingelheim setzt auf Veeva Vault CRM | Veeva Systems Europe","og:description":"F\u00fchrendes Biopharmaunternehmen entscheidet sich f\u00fcr Life-Sciences-CRM der n\u00e4chsten Generation als Fundament f\u00fcr die zuk\u00fcnftige Expansion und f\u00fcr Produkteinf\u00fchrungen.","og:url":"https:\/\/www.veeva.com\/eu\/de\/ressourcen\/boehringer-ingelheim-setzt-auf-veeva-vault-crm\/","og:image":"https:\/\/www.veeva.com\/eu\/wp-content\/uploads\/2024\/10\/resource-tile-boehringer-340x240@2x.png","og:image:secure_url":"https:\/\/www.veeva.com\/eu\/wp-content\/uploads\/2024\/10\/resource-tile-boehringer-340x240@2x.png","og:image:width":"680","og:image:height":"480","article:published_time":"2024-11-14T14:01:08+00:00","article:modified_time":"2025-10-21T10:13:32+00:00","twitter:card":"summary_large_image","twitter:title":"Boehringer Ingelheim setzt auf Veeva Vault CRM | Veeva Systems Europe","twitter:description":"F\u00fchrendes Biopharmaunternehmen entscheidet sich f\u00fcr Life-Sciences-CRM der n\u00e4chsten Generation als Fundament f\u00fcr die zuk\u00fcnftige Expansion und f\u00fcr Produkteinf\u00fchrungen.","twitter:image":"https:\/\/www.veeva.com\/eu\/wp-content\/uploads\/2024\/10\/resource-tile-boehringer-340x240@2x.png"},"aioseo_meta_data":{"post_id":"80340","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"featured","og_image_url":"https:\/\/www.veeva.com\/eu\/wp-content\/uploads\/2024\/10\/resource-tile-boehringer-340x240@2x.png","og_image_width":"680","og_image_height":"480","og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":true,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"limit_modified_date":false,"open_ai":"{\"title\":{\"suggestions\":[],\"usage\":0},\"description\":{\"suggestions\":[],\"usage\":0}}","created":"2024-11-14 13:35:46","updated":"2026-08-24 21:12:19","focus_keyword":null,"additional_keywords":null,"truseo_locale":null,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":"2026-08-24 21:12:19"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.veeva.com\/eu\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.veeva.com\/eu\/de\/ressourcen\/\" title=\"Resources - DE\">Resources - DE<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.veeva.com\/eu\/resources-de-canonical\/unique\/\" title=\"Make Unique\">Make Unique<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tBoehringer Ingelheim setzt auf Veeva Vault CRM\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.veeva.com\/eu"},{"label":"Resources - DE","link":"https:\/\/www.veeva.com\/eu\/de\/ressourcen\/"},{"label":"Make Unique","link":"https:\/\/www.veeva.com\/eu\/resources-de-canonical\/unique\/"},{"label":"Boehringer Ingelheim setzt auf Veeva Vault CRM","link":"https:\/\/www.veeva.com\/eu\/de\/ressourcen\/boehringer-ingelheim-setzt-auf-veeva-vault-crm\/"}],"_links":{"self":[{"href":"https:\/\/www.veeva.com\/eu\/wp-json\/wp\/v2\/resources_de\/80340","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.veeva.com\/eu\/wp-json\/wp\/v2\/resources_de"}],"about":[{"href":"https:\/\/www.veeva.com\/eu\/wp-json\/wp\/v2\/types\/resources_de"}],"version-history":[{"count":1,"href":"https:\/\/www.veeva.com\/eu\/wp-json\/wp\/v2\/resources_de\/80340\/revisions"}],"predecessor-version":[{"id":80343,"href":"https:\/\/www.veeva.com\/eu\/wp-json\/wp\/v2\/resources_de\/80340\/revisions\/80343"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.veeva.com\/eu\/wp-json\/wp\/v2\/media\/80326"}],"wp:attachment":[{"href":"https:\/\/www.veeva.com\/eu\/wp-json\/wp\/v2\/media?parent=80340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}