{"id":70042,"date":"2023-03-24T10:23:41","date_gmt":"2023-03-24T09:23:41","guid":{"rendered":"https:\/\/www.veeva.com\/eu\/?post_type=resources_fr&#038;p=70042"},"modified":"2026-04-09T15:38:41","modified_gmt":"2026-04-09T13:38:41","slug":"veeva-et-msd-concluent-un-partenariat-strategique-a-long-terme","status":"publish","type":"resources_fr","link":"https:\/\/www.veeva.com\/eu\/fr\/ressources\/veeva-et-msd-concluent-un-partenariat-strategique-a-long-terme\/","title":{"rendered":"Veeva et MSD concluent un partenariat strat\u00e9gique \u00e0 long terme"},"content":{"rendered":"<p align=\"center\"><em>Ce partenariat de dix ans aidera MSD \u00e0 r\u00e9duire ses co\u00fbts op\u00e9rationnels, \u00e0 cr\u00e9er de la valeur pour les patients et \u00e0 optimiser l&#8217;exp\u00e9rience des professionnels de la sant\u00e9 et des patients<br \/>\n<\/em><\/p>\n<p><strong>BARCELONE, Espagne, 2 novembre 2022 &#8211; <\/strong> <a href=\"\/fr\/eu\/\">Veeva Systems<\/a> a annonc\u00e9 aujourd&#8217;hui avoir conclu un accord de partenariat strat\u00e9gique de dix ans avec Merck (NYSE : MRK), connu sous le nom de MSD hors des \u00c9tats-Unis et du Canada, qui s&#8217;appuie sur le partenariat existant de douze ans qui lie les deux soci\u00e9t\u00e9s. Selon les termes de l&#8217;accord, MSD adoptera l&#8217;approche \u00ab Veeva d&#8217;abord \u00bb en ce qui concerne les nouveaux logiciels et donn\u00e9es sp\u00e9cifiques \u00e0 son secteur d&#8217;activit\u00e9, en privil\u00e9giant les produits Veeva lorsqu&#8217;ils sont adapt\u00e9s \u00e0 l&#8217;objectif vis\u00e9, afin d&#8217;optimiser la valeur de la plateforme et des produits int\u00e9gr\u00e9s de Veeva bas\u00e9s dans le cloud. Veeva proposera \u00e0 MSD une approche strat\u00e9gique de la tarification et MSD participera \u00e0 l&#8217;\u00e9laboration de la feuille de route des produits de Veeva. Ce partenariat permettra d&#8217;acc\u00e9l\u00e9rer la strat\u00e9gie num\u00e9rique de MSD et de renforcer l&#8217;efficacit\u00e9 de l&#8217;\u00e9valuation, de l&#8217;achat, de l&#8217;exploitation et de la cr\u00e9ation de valeur \u00e0 partir des produits et services de Veeva.\n<\/p>\n<p>\u00ab La transformation de notre potentiel num\u00e9rique, de nos donn\u00e9es et de nos capacit\u00e9s d&#8217;analyse est essentielle pour permettre \u00e0 nos coll\u00e8gues internationaux de r\u00e9aliser notre objectif : utiliser le pouvoir de la science de pointe pour sauver et am\u00e9liorer des vies dans le monde entier \u00bb, a d\u00e9clar\u00e9 Robert M. Davis, directeur g\u00e9n\u00e9ral et pr\u00e9sident de MSD. \u00ab Notre partenariat strat\u00e9gique avec Veeva accro\u00eet notre capacit\u00e9 \u00e0 exploiter des technologies innovantes et am\u00e9liore notre capacit\u00e9 \u00e0 cr\u00e9er de la valeur pour les patients et toutes nos parties prenantes &#8211; c&#8217;est un \u00e9l\u00e9ment cl\u00e9 de la fa\u00e7on dont nous mesurons le succ\u00e8s. \u00bb\n <\/p>\n<p>\u00ab Je suis ravi de voir notre partenariat avec MSD \u00e9voluer vers ce niveau strat\u00e9gique \u00bb, a d\u00e9clar\u00e9 Peter Gassner, PDG de Veeva \u00ab Nos \u00e9quipes ont une m\u00eame passion pour l&#8217;industrie et une m\u00eame compr\u00e9hension du partenariat strat\u00e9gique. Je suis impatient de voir ce que nous allons cr\u00e9er ensemble dans les ann\u00e9es \u00e0 venir. \u00bb <\/p>\n<p><strong>Informations compl\u00e9mentaires<\/strong><\/p>\n<p>Connectez-vous avec Veeva sur LinkedIn : <a href=\"http:\/\/www.linkedin.com\/company\/veeva-systems\" target=\"_blank\" rel=\"noopener noreferrer\">linkedin.com\/company\/veeva-systems<\/a><\/p>\n<p><strong>\u00c0 propos de Veeva Systems<\/strong><\/p>\n<p>Veeva est le leader mondial des logiciels Cloud pour l\u2019industrie des sciences de la vie. Pariant sur l\u2019innovation, l\u2019excellence des produits, et la r\u00e9ussite de ses clients, Veeva compte plus de 1 100 clients, allant des plus grandes entreprises pharmaceutiques mondiales aux soci\u00e9t\u00e9s de biotechnologie \u00e9mergentes. En tant que soci\u00e9t\u00e9 d\u2019int\u00e9r\u00eat public, Veeva s\u2019engage \u00e0 concilier au mieux les int\u00e9r\u00eats de toutes les parties prenantes, y compris les clients, les employ\u00e9s, les actionnaires et les industries qu\u2019elle sert. Pour en savoir plus, rendez-vous sur <a href=\"\/eu\/fr\/\">veeva.com\/eu\/fr<\/a>.<\/p>\n<\/p>\n<p><strong>D\u00e9clarations prospectives de Veeva<\/strong><\/p>\n<p>Ce communiqu\u00e9 contient des d\u00e9clarations prospectives concernant les produits et services de Veeva et les r\u00e9sultats ou avantages attendus de l&#8217;utilisation de nos produits et services, y compris certaines de nos nouvelles solutions et applications qui sont encore en cours de d\u00e9veloppement ou qui ne sont pas g\u00e9n\u00e9ralement disponibles. Ces d\u00e9clarations sont fond\u00e9es sur nos attentes actuelles. Les r\u00e9sultats r\u00e9els, la disponibilit\u00e9 et tout \u00e9v\u00e9nement futur concernant ces produits et services pourraient diff\u00e9rer sensiblement de ceux fournis dans ce communiqu\u00e9 et nous n&#8217;avons aucune obligation de mettre \u00e0 jour ces d\u00e9clarations. Il existe de nombreux risques susceptibles d&#8217;avoir un impact n\u00e9gatif sur nos r\u00e9sultats, y compris les risques et incertitudes divulgu\u00e9s dans notre formulaire 10-Q pour la p\u00e9riode se terminant le 31 juillet 2022, que vous pouvez trouver <a href=\"https:\/\/www.sec.gov\/ix?doc=\/Archives\/edgar\/data\/1393052\/000139305222000036\/veev-20220731.htm\" rel=\"noopener noreferrer\" target=\"_blank\">ici<\/a> (un r\u00e9sum\u00e9 des risques susceptibles d&#8217;avoir un impact sur notre activit\u00e9 se trouve aux pages 39 et 40), et dans nos d\u00e9p\u00f4ts ult\u00e9rieurs aupr\u00e8s de la SEC, auxquels vous pouvez acc\u00e9der sur <a href=\"https:\/\/www.sec.gov\/\" rel=\"noopener noreferrer\" target=\"_blank\">sec.gov<\/a>.<\/p>\n<p>###<\/p>\n<p><strong>Contact presse :<\/strong><\/p>\n<p>BCW France pour Veeva : <a href=\"mailto:veeva@bcw-global.com\">veeva@bcw-global.com<\/a><\/p>\n<p>Jeremy Whittaker<br \/>\nVeeva Systems<br \/>\n+49 6950955486<br \/>\n<a href=\"mailto:jeremy.whittaker@veeva.com\n\">jeremy.whittaker@veeva.com<br \/>\n<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ce partenariat de dix ans aidera Merck \u00e0 r\u00e9duire ses co\u00fbts op\u00e9rationnels, \u00e0 cr\u00e9er de la valeur pour les patients et \u00e0 optimiser l&#8217;exp\u00e9rience des professionnels de la sant\u00e9 et des patients<\/p>\n","protected":false},"featured_media":67331,"parent":0,"template":"","class_list":["post-70042","resources_fr","type-resources_fr","status-publish","has-post-thumbnail","hentry","resources-fr-canonical-unique","resource-html-content-yes","resource-fr-type-communiques-de-presse","resource-fr-area-commercial","resource-fr-area-area-vault-platform","resource-fr-product-approved-email","resource-fr-product-campaign-manager","resource-fr-product-clm","resource-fr-product-commercial-content-promomats","resource-fr-product-crm","resource-fr-product-digital-engagement-engage","resource-fr-product-events-management","resource-fr-product-field-planning-alignments-align-territory-designer","resource-fr-product-key-account-management","resource-fr-product-network-mdm","resource-fr-product-product-vault-platform"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Ce partenariat de dix ans aidera Merck \u00e0 r\u00e9duire ses co\u00fbts op\u00e9rationnels, \u00e0 cr\u00e9er de la valeur pour les patients et \u00e0 optimiser l&#039;exp\u00e9rience des professionnels de la sant\u00e9 et des patients\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.veeva.com\/eu\/fr\/ressources\/veeva-et-msd-concluent-un-partenariat-strategique-a-long-terme\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Veeva Systems Europe\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Veeva et MSD concluent un partenariat strat\u00e9gique \u00e0 long terme | Veeva Systems Europe\" \/>\n\t\t<meta property=\"og:description\" content=\"Ce partenariat de dix ans aidera Merck \u00e0 r\u00e9duire ses co\u00fbts op\u00e9rationnels, \u00e0 cr\u00e9er de la valeur pour les patients et \u00e0 optimiser l&#039;exp\u00e9rience des professionnels de la sant\u00e9 et des patients\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.veeva.com\/eu\/fr\/ressources\/veeva-et-msd-concluent-un-partenariat-strategique-a-long-terme\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.veeva.com\/eu\/wp-content\/uploads\/2023\/03\/NDA-PR-Social_FR.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.veeva.com\/eu\/wp-content\/uploads\/2023\/03\/NDA-PR-Social_FR.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-03-24T09:23:41+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-04-09T13:38:41+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Veeva et MSD concluent un partenariat strat\u00e9gique \u00e0 long terme | Veeva Systems Europe\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Ce partenariat de dix ans aidera Merck \u00e0 r\u00e9duire ses co\u00fbts op\u00e9rationnels, \u00e0 cr\u00e9er de la valeur pour les patients et \u00e0 optimiser l&#039;exp\u00e9rience des professionnels de la sant\u00e9 et des patients\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.veeva.com\/eu\/wp-content\/uploads\/2023\/03\/NDA-PR-Social_FR.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/fr\\\/ressources\\\/veeva-et-msd-concluent-un-partenariat-strategique-a-long-terme\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.veeva.com\\\/eu\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/fr\\\/ressources\\\/#listItem\",\"name\":\"Resources - FR\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/fr\\\/ressources\\\/#listItem\",\"position\":2,\"name\":\"Resources - FR\",\"item\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/fr\\\/ressources\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/resources-fr-canonical\\\/unique\\\/#listItem\",\"name\":\"Make Unique\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/resources-fr-canonical\\\/unique\\\/#listItem\",\"position\":3,\"name\":\"Make Unique\",\"item\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/resources-fr-canonical\\\/unique\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/fr\\\/ressources\\\/veeva-et-msd-concluent-un-partenariat-strategique-a-long-terme\\\/#listItem\",\"name\":\"Veeva et MSD concluent un partenariat strat\\u00e9gique \\u00e0 long terme\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/fr\\\/ressources\\\/#listItem\",\"name\":\"Resources - FR\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/fr\\\/ressources\\\/veeva-et-msd-concluent-un-partenariat-strategique-a-long-terme\\\/#listItem\",\"position\":4,\"name\":\"Veeva et MSD concluent un partenariat strat\\u00e9gique \\u00e0 long terme\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/resources-fr-canonical\\\/unique\\\/#listItem\",\"name\":\"Make Unique\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/#organization\",\"name\":\"Veeva Systems Europe\",\"description\":\"EU Site\",\"url\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/fr\\\/ressources\\\/veeva-et-msd-concluent-un-partenariat-strategique-a-long-terme\\\/#webpage\",\"url\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/fr\\\/ressources\\\/veeva-et-msd-concluent-un-partenariat-strategique-a-long-terme\\\/\",\"name\":\"Veeva et MSD concluent un partenariat strat\\u00e9gique \\u00e0 long terme | Veeva Systems Europe\",\"description\":\"Ce partenariat de dix ans aidera Merck \\u00e0 r\\u00e9duire ses co\\u00fbts op\\u00e9rationnels, \\u00e0 cr\\u00e9er de la valeur pour les patients et \\u00e0 optimiser l'exp\\u00e9rience des professionnels de la sant\\u00e9 et des patients\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/fr\\\/ressources\\\/veeva-et-msd-concluent-un-partenariat-strategique-a-long-terme\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/NDA-PR-Veeva-Logo-Tile.png\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/fr\\\/ressources\\\/veeva-et-msd-concluent-un-partenariat-strategique-a-long-terme\\\/#mainImage\",\"width\":710,\"height\":501,\"caption\":\"NDA PR Veeva Logo Tile\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/fr\\\/ressources\\\/veeva-et-msd-concluent-un-partenariat-strategique-a-long-terme\\\/#mainImage\"},\"datePublished\":\"2023-03-24T10:23:41+01:00\",\"dateModified\":\"2026-04-09T15:38:41+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/#website\",\"url\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/\",\"name\":\"Veeva Systems Europe\",\"description\":\"EU Site\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Veeva et MSD concluent un partenariat strat\u00e9gique \u00e0 long terme | Veeva Systems Europe<\/title>\n\n","aioseo_head_json":{"title":"Veeva et MSD concluent un partenariat strat\u00e9gique \u00e0 long terme | Veeva Systems Europe","description":"Ce partenariat de dix ans aidera Merck \u00e0 r\u00e9duire ses co\u00fbts op\u00e9rationnels, \u00e0 cr\u00e9er de la valeur pour les patients et \u00e0 optimiser l'exp\u00e9rience des professionnels de la sant\u00e9 et des patients","canonical_url":"https:\/\/www.veeva.com\/eu\/fr\/ressources\/veeva-et-msd-concluent-un-partenariat-strategique-a-long-terme\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.veeva.com\/eu\/fr\/ressources\/veeva-et-msd-concluent-un-partenariat-strategique-a-long-terme\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.veeva.com\/eu#listItem","position":1,"name":"Home","item":"https:\/\/www.veeva.com\/eu","nextItem":{"@type":"ListItem","@id":"https:\/\/www.veeva.com\/eu\/fr\/ressources\/#listItem","name":"Resources - FR"}},{"@type":"ListItem","@id":"https:\/\/www.veeva.com\/eu\/fr\/ressources\/#listItem","position":2,"name":"Resources - FR","item":"https:\/\/www.veeva.com\/eu\/fr\/ressources\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.veeva.com\/eu\/resources-fr-canonical\/unique\/#listItem","name":"Make Unique"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.veeva.com\/eu#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.veeva.com\/eu\/resources-fr-canonical\/unique\/#listItem","position":3,"name":"Make Unique","item":"https:\/\/www.veeva.com\/eu\/resources-fr-canonical\/unique\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.veeva.com\/eu\/fr\/ressources\/veeva-et-msd-concluent-un-partenariat-strategique-a-long-terme\/#listItem","name":"Veeva et MSD concluent un partenariat strat\u00e9gique \u00e0 long terme"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.veeva.com\/eu\/fr\/ressources\/#listItem","name":"Resources - FR"}},{"@type":"ListItem","@id":"https:\/\/www.veeva.com\/eu\/fr\/ressources\/veeva-et-msd-concluent-un-partenariat-strategique-a-long-terme\/#listItem","position":4,"name":"Veeva et MSD concluent un partenariat strat\u00e9gique \u00e0 long terme","previousItem":{"@type":"ListItem","@id":"https:\/\/www.veeva.com\/eu\/resources-fr-canonical\/unique\/#listItem","name":"Make Unique"}}]},{"@type":"Organization","@id":"https:\/\/www.veeva.com\/eu\/#organization","name":"Veeva Systems Europe","description":"EU Site","url":"https:\/\/www.veeva.com\/eu\/"},{"@type":"WebPage","@id":"https:\/\/www.veeva.com\/eu\/fr\/ressources\/veeva-et-msd-concluent-un-partenariat-strategique-a-long-terme\/#webpage","url":"https:\/\/www.veeva.com\/eu\/fr\/ressources\/veeva-et-msd-concluent-un-partenariat-strategique-a-long-terme\/","name":"Veeva et MSD concluent un partenariat strat\u00e9gique \u00e0 long terme | Veeva Systems Europe","description":"Ce partenariat de dix ans aidera Merck \u00e0 r\u00e9duire ses co\u00fbts op\u00e9rationnels, \u00e0 cr\u00e9er de la valeur pour les patients et \u00e0 optimiser l'exp\u00e9rience des professionnels de la sant\u00e9 et des patients","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/www.veeva.com\/eu\/#website"},"breadcrumb":{"@id":"https:\/\/www.veeva.com\/eu\/fr\/ressources\/veeva-et-msd-concluent-un-partenariat-strategique-a-long-terme\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/www.veeva.com\/eu\/wp-content\/uploads\/2022\/11\/NDA-PR-Veeva-Logo-Tile.png","@id":"https:\/\/www.veeva.com\/eu\/fr\/ressources\/veeva-et-msd-concluent-un-partenariat-strategique-a-long-terme\/#mainImage","width":710,"height":501,"caption":"NDA PR Veeva Logo Tile"},"primaryImageOfPage":{"@id":"https:\/\/www.veeva.com\/eu\/fr\/ressources\/veeva-et-msd-concluent-un-partenariat-strategique-a-long-terme\/#mainImage"},"datePublished":"2023-03-24T10:23:41+01:00","dateModified":"2026-04-09T15:38:41+02:00"},{"@type":"WebSite","@id":"https:\/\/www.veeva.com\/eu\/#website","url":"https:\/\/www.veeva.com\/eu\/","name":"Veeva Systems Europe","description":"EU Site","inLanguage":"en-US","publisher":{"@id":"https:\/\/www.veeva.com\/eu\/#organization"}}]},"og:locale":"en_US","og:site_name":"Veeva Systems Europe","og:type":"article","og:title":"Veeva et MSD concluent un partenariat strat\u00e9gique \u00e0 long terme | Veeva Systems Europe","og:description":"Ce partenariat de dix ans aidera Merck \u00e0 r\u00e9duire ses co\u00fbts op\u00e9rationnels, \u00e0 cr\u00e9er de la valeur pour les patients et \u00e0 optimiser l'exp\u00e9rience des professionnels de la sant\u00e9 et des patients","og:url":"https:\/\/www.veeva.com\/eu\/fr\/ressources\/veeva-et-msd-concluent-un-partenariat-strategique-a-long-terme\/","og:image":"https:\/\/www.veeva.com\/eu\/wp-content\/uploads\/2023\/03\/NDA-PR-Social_FR.png","og:image:secure_url":"https:\/\/www.veeva.com\/eu\/wp-content\/uploads\/2023\/03\/NDA-PR-Social_FR.png","og:image:width":1200,"og:image:height":630,"article:published_time":"2023-03-24T09:23:41+00:00","article:modified_time":"2026-04-09T13:38:41+00:00","twitter:card":"summary_large_image","twitter:title":"Veeva et MSD concluent un partenariat strat\u00e9gique \u00e0 long terme | Veeva Systems Europe","twitter:description":"Ce partenariat de dix ans aidera Merck \u00e0 r\u00e9duire ses co\u00fbts op\u00e9rationnels, \u00e0 cr\u00e9er de la valeur pour les patients et \u00e0 optimiser l'exp\u00e9rience des professionnels de la sant\u00e9 et des patients","twitter:image":"https:\/\/www.veeva.com\/eu\/wp-content\/uploads\/2023\/03\/NDA-PR-Social_FR.png"},"aioseo_meta_data":{"post_id":"70042","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"custom_image","og_image_url":"https:\/\/www.veeva.com\/eu\/wp-content\/uploads\/2023\/03\/NDA-PR-Social_FR.png","og_image_width":"1200","og_image_height":"630","og_image_custom_url":"https:\/\/www.veeva.com\/eu\/wp-content\/uploads\/2023\/03\/NDA-PR-Social_FR.png","og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"custom_image","twitter_image_url":"https:\/\/www.veeva.com\/eu\/wp-content\/uploads\/2023\/03\/NDA-PR-Social_FR.png","twitter_image_custom_url":"https:\/\/www.veeva.com\/eu\/wp-content\/uploads\/2023\/03\/NDA-PR-Social_FR.png","twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"limit_modified_date":false,"open_ai":"{\"title\":{\"suggestions\":[],\"usage\":0},\"description\":{\"suggestions\":[],\"usage\":0}}","created":"2023-03-24 09:18:00","updated":"2026-08-24 23:49:38","focus_keyword":null,"additional_keywords":null,"truseo_locale":null,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":"2026-08-24 23:49:38"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.veeva.com\/eu\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.veeva.com\/eu\/fr\/ressources\/\" title=\"Resources - FR\">Resources - FR<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.veeva.com\/eu\/resources-fr-canonical\/unique\/\" title=\"Make Unique\">Make Unique<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tVeeva et MSD concluent un partenariat strat\u00e9gique \u00e0 long terme\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.veeva.com\/eu"},{"label":"Resources - FR","link":"https:\/\/www.veeva.com\/eu\/fr\/ressources\/"},{"label":"Make Unique","link":"https:\/\/www.veeva.com\/eu\/resources-fr-canonical\/unique\/"},{"label":"Veeva et MSD concluent un partenariat strat\u00e9gique \u00e0 long terme","link":"https:\/\/www.veeva.com\/eu\/fr\/ressources\/veeva-et-msd-concluent-un-partenariat-strategique-a-long-terme\/"}],"_links":{"self":[{"href":"https:\/\/www.veeva.com\/eu\/wp-json\/wp\/v2\/resources_fr\/70042","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.veeva.com\/eu\/wp-json\/wp\/v2\/resources_fr"}],"about":[{"href":"https:\/\/www.veeva.com\/eu\/wp-json\/wp\/v2\/types\/resources_fr"}],"version-history":[{"count":1,"href":"https:\/\/www.veeva.com\/eu\/wp-json\/wp\/v2\/resources_fr\/70042\/revisions"}],"predecessor-version":[{"id":70043,"href":"https:\/\/www.veeva.com\/eu\/wp-json\/wp\/v2\/resources_fr\/70042\/revisions\/70043"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.veeva.com\/eu\/wp-json\/wp\/v2\/media\/67331"}],"wp:attachment":[{"href":"https:\/\/www.veeva.com\/eu\/wp-json\/wp\/v2\/media?parent=70042"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}