{"id":86791,"date":"2025-08-18T15:37:04","date_gmt":"2025-08-18T13:37:04","guid":{"rendered":"https:\/\/www.veeva.com\/eu\/?post_type=resources_fr&#038;p=86791"},"modified":"2026-04-09T15:18:54","modified_gmt":"2026-04-09T13:18:54","slug":"iqvia-et-veeva-annoncent-des-partenariats-cliniques-et-commerciaux-a-long-terme-ainsi-que-la-resolution-de-leurs-litiges","status":"publish","type":"resources_fr","link":"https:\/\/www.veeva.com\/eu\/fr\/ressources\/iqvia-et-veeva-annoncent-des-partenariats-cliniques-et-commerciaux-a-long-terme-ainsi-que-la-resolution-de-leurs-litiges\/","title":{"rendered":"IQVIA et Veeva annoncent des partenariats cliniques et commerciaux \u00e0 long terme ainsi que la r\u00e9solution de leurs litiges"},"content":{"rendered":"<p align=\"center\"><i>Ces accords de partenariats mondiaux ont pour objectif d\u2019aider les clients \u00e0 am\u00e9liorer l\u2019efficacit\u00e9 et la performance cliniques et commerciales<\/p>\n<p><strong>RESEARCH TRIANGLE PARK, N.C. and PLEASANTON, Calif. \u2014 18 Ao\u00fbt, 2025 \u2014 <\/strong> <a href=\"https:\/\/www.iqvia.com\" target=\"_blank\" rel=\"noopener\">IQVIA<\/a> (NYSE: IQV) et <a href=\"\/\" target=\"_blank\" rel=\"noopener\">Veeva Systems<\/a> (NYSE: VEEV) ont annonc\u00e9 aujourd\u2019hui des partenariats cliniques et commerciaux mondiaux ainsi que la r\u00e9solution compl\u00e8te de tous les litiges juridiques en cours. Selon les termes de cet accord \u00e0 long terme, les clients pourront utiliser ensemble, de mani\u00e8re simple et efficace, les logiciels, donn\u00e9es, technologies et services propos\u00e9s par Veeva et IQVIA.<\/p>\n<p>Ces partenariats mondiaux vont permettre aux clients de collaborer facilement avec IQVIA et Veeva dans des domaines cl\u00e9s, notamment :<\/p>\n<ul>\n<li><strong>Commercial<\/strong> : Les deux entreprises ont \u00e9tabli des accords d\u2019acc\u00e8s tiers (TPA) pour les donn\u00e9es de r\u00e9f\u00e9rence et les logiciels. Ces accords permettent aux clients d&#8217;utiliser les donn\u00e9es d&#8217;une entreprise avec les logiciels ou les services de l&#8217;autre. Cela inclut l\u2019utilisation des donn\u00e9es IQVIA dans Veeva Network pour la gestion des donn\u00e9es de r\u00e9f\u00e9rence (MDM), Veeva Nitro pour l\u2019analytique, et Veeva AI. En plus de l\u2019utilisation des donn\u00e9es Veeva avec les produits et services commerciaux d\u2019IQVIA, cette derni\u00e8re a rejoint les programmes partenaires de Veeva dans les domaines de la technologie, de l\u2019IA et des services, afin de soutenir l\u2019int\u00e9gration des logiciels Veeva avec IQVIA Analytics, IQVIA Information Management (y compris MDM), IQVIA Agentic AI et les offres d\u2019orchestration commerciale d\u2019IQVIA. Gr\u00e2ce \u00e0 ces nouveaux partenariats, les clients b\u00e9n\u00e9ficient d\u00e9sormais d&#8217;un processus simple et rapide pour obtenir les autorisations d&#8217;acc\u00e8s tiers n\u00e9cessaires \u00e0 leurs projets.<\/li>\n<li><strong>Recherche Clinique<\/strong> : IQVIA a rejoint le programme CRO Clinical Data Partner de Veeva et pourra exploiter la suite clinique de Veeva pour mener des essais cliniques \u00e0 l\u2019aide des logiciels Veeva, y compris la conception d\u2019\u00e9tudes avec Veeva EDC. Gr\u00e2ce \u00e0 ce partenariat, les clients b\u00e9n\u00e9ficieront de l\u2019expertise d\u2019IQVIA en gestion des donn\u00e9es cliniques, en solutions technologiques cliniques et en programmation EDC, associ\u00e9e aux logiciels Veeva, afin d\u2019acc\u00e9l\u00e9rer la cr\u00e9ation de bases de donn\u00e9es, la cl\u00f4ture des \u00e9tudes et la livraison des donn\u00e9es.<\/li>\n<\/ul>\n<p>\u00ab Nous nous engageons \u00e0 soutenir une int\u00e9gration fluide des produits et services avec IQVIA, au b\u00e9n\u00e9fice de nos clients communs et de l\u2019ensemble du secteur \u00bb, a d\u00e9clar\u00e9 Peter Gassner, founder et CEO de Veeva. \u00ab Je me r\u00e9jouis du potentiel de nos partenariats cliniques et commerciaux pour apporter une valeur consid\u00e9rable \u00e0 nos clients communs. \u00bb<\/p>\n<p>\u00ab Les partenariats entre IQVIA et Veeva r\u00e9unissent des capacit\u00e9s de premier plan dans les domaines de l\u2019information, de l\u2019IA, de la technologie et des services pour nos clients communs \u00bb, a d\u00e9clar\u00e9 Ari Bousbib, chairman et CEO d\u2019IQVIA. \u00ab Cela permettra aux clients d\u2019IQVIA utilisant les plateformes Veeva d\u2019acc\u00e9l\u00e9rer le d\u00e9veloppement clinique, de mettre plus efficacement les traitements sur le march\u00e9 et d\u2019am\u00e9liorer l\u2019acc\u00e8s des patients aux innovations. \u00bb<\/p>\n<p>Pour plus d\u2019informations, visitez la page <a href=\"https:\/\/www.iqvia.com\/Veeva\" target=\"_blank\" rel=\"noopener\">Veeva Partnerships<\/a> sur iqvia.com ou <a href=\"https:\/\/www.veeva.com\/iqvia\/\">IQVIA Partnerships<\/a> sur veeva.com.<\/p>\n<p><strong>A propos de IQVIA<\/strong><br \/>\nIQVIA (NYSE : IQV) est un leader mondial dans la prestation de services de recherche clinique, d\u2019analyses commerciales et d\u2019informations strat\u00e9giques pour les industries des sciences de la vie et de la sant\u00e9. Le portefeuille de solutions d\u2019IQVIA est optimis\u00e9 par IQVIA Connected Intelligence&#x2122;, afin de fournir des analyses exploitables et des services bas\u00e9s sur des donn\u00e9es de sant\u00e9 de haute qualit\u00e9, Healthcare-grade AI\u00ae, des analyses avanc\u00e9es, les technologies les plus r\u00e9centes et une expertise sectorielle approfondie. IQVIA s\u2019engage \u00e0 utiliser l\u2019intelligence artificielle de mani\u00e8re responsable, avec des capacit\u00e9s aliment\u00e9es par l\u2019IA reposant sur des approches de pointe en mati\u00e8re de confidentialit\u00e9, de conformit\u00e9 r\u00e9glementaire et de s\u00e9curit\u00e9 des patients, et \u00e0 fournir une IA r\u00e9pondant aux plus hauts standards de confiance et de pr\u00e9cision exig\u00e9s par le secteur. Avec environ 89 000 employ\u00e9s r\u00e9partis dans plus de 100 pays, comprenant des experts en sant\u00e9, sciences de la vie, analyse de donn\u00e9es, technologie et excellence op\u00e9rationnelle, IQVIA se consacre \u00e0 acc\u00e9l\u00e9rer le d\u00e9veloppement et la commercialisation de traitements m\u00e9dicaux innovants afin d\u2019am\u00e9liorer les r\u00e9sultats pour les patients et la sant\u00e9 des populations \u00e0 travers le monde.<\/p>\n<p>IQVIA est \u00e9galement un leader mondial dans la protection de la confidentialit\u00e9 des patients. L\u2019entreprise utilise un large \u00e9ventail de technologies et de dispositifs de protection renfor\u00e7ant la confidentialit\u00e9, afin de pr\u00e9server la vie priv\u00e9e tout en g\u00e9n\u00e9rant et en analysant des informations \u00e0 grande \u00e9chelle. Les capacit\u00e9s d\u2019analyse et d\u2019ex\u00e9cution d\u2019IQVIA aident les entreprises de biotechnologie, de dispositifs m\u00e9dicaux et pharmaceutiques, les chercheurs m\u00e9dicaux, les agences gouvernementales, les assureurs et autres acteurs du secteur de la sant\u00e9 \u00e0 acc\u00e9der \u00e0 une compr\u00e9hension plus approfondie des maladies, des comportements humains et des avanc\u00e9es scientifiques, dans le but de progresser vers des traitements curatifs.Pour en savoir plus, visitez <a href=\"http:\/\/www.iqvia.com\" target=\"_blank\" rel=\"noopener\">www.iqvia.com<\/a>.<\/p>\n<p><strong>A propos de Veeva Systems<\/strong><br \/>\nVeeva est le leader mondial des logiciels Cloud pour l\u2019industrie des sciences de la vie. Pariant sur l\u2019innovation, l\u2019excellence de ses produits et la r\u00e9ussite de ses clients, Veeva compte plus de 1000 clients, des plus grandes entreprises pharmaceutiques mondiales aux soci\u00e9t\u00e9s de biotechnologie \u00e9mergentes. En tant que <a href=\"https:\/\/www.veeva.com\/pbc\/\" target=\"_blank\" rel=\"noopener\">soci\u00e9t\u00e9 d&#8217;int\u00e9r\u00eat public<\/a>, Veeva s&#8217;engage \u00e0 concilier au mieux les int\u00e9r\u00eats de toutes les parties prenantes, y compris les clients, les employ\u00e9s, les actionnaires et les industries qu&#8217;elle sert. Pour en savoir plus, rendez-vous sur <a href=\"\/eu\/fr\/\">veeva.com\/eu\/fr<\/a>.<\/p>\n<p><strong>D\u00e9claration prospective de Veeva<\/strong><br \/>\nCette publication contient des d\u00e9clarations prospectives concernant les r\u00e9sultats et les avantages attendus des partenariats de Veeva avec IQVIA. Ces d\u00e9clarations sont bas\u00e9es sur nos attentes actuelles. Les r\u00e9sultats r\u00e9els pourraient diff\u00e9rer sensiblement de ceux fournis dans cette publication et nous n&#8217;avons aucune obligation de mettre \u00e0 jour ces d\u00e9clarations.<\/p>\n<p><center><\/p>\n<p>###<\/p>\n<p><\/center><\/p>\n<p><strong>Contacts:<\/strong> <\/p>\n<div class=\"row\">\n<div class=\"col-sm-6\">\n<p>\n\t\tMaria Scurry<br \/>\n\t\tVeeva Media Relations<br \/>\n\t\t781-366-7617<br \/>\n\t\t<a href=\"mailto:maria.scurry@veeva.com\">maria.scurry@veeva.com<\/a>\n\t\t<\/p>\n<p>\n\t\tGunnar Hansen<br \/>\n\t\tVeeva Investor Relations<br \/>\n\t\t267-460-5839<br \/>\n\t\t<a href=\"mailto:gunnar.hansen@veeva.com\">gunnar.hansen@veeva.com<\/a>\n\t\t<\/p>\n<\/p><\/div>\n<div class=\"col-sm-6\">\n<p>\n\t\tAlissa Maupin<br \/>\n\t\tIQVIA Media Relations <br \/>\n\t\t919-923-6785 <br \/>\n\t\t<a href=\"mailto:alissa.maupin1@iqvia.com\">alissa.maupin1@iqvia.com<\/a>\n\t\t<\/p>\n<p>\n\t\tKerri Joseph<br \/>\n\t\tIQVIA Investor Relations <br \/>\n\t\t973-541-3558 <br \/>\n\t\t<a href=\"mailto:kerri.joseph@iqvia.com\">kerri.joseph@iqvia.com<\/a>\n\t\t<\/p>\n<\/p><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ces accords de partenariats mondiaux ont pour objectif d\u2019aider les clients \u00e0 am\u00e9liorer l\u2019efficacit\u00e9 et la performance cliniques et commerciales.<\/p>\n","protected":false},"featured_media":86688,"parent":0,"template":"","class_list":["post-86791","resources_fr","type-resources_fr","status-publish","has-post-thumbnail","hentry","resources-fr-canonical-unique","resource-html-content-yes","resource-fr-type-communiques-de-presse","resource-fr-area-commercial","resource-fr-area-donnees","resource-fr-area-donnees-cliniques","resource-fr-product-deep-kol-data-link","resource-fr-product-dqs","resource-fr-product-ecoa","resource-fr-product-edc","resource-fr-product-hcp-access-data","resource-fr-product-reference-data-opendata-clinical","resource-fr-product-reference-data-opendata"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Ces accords de partenariats mondiaux ont pour objectif d\u2019aider les clients \u00e0 am\u00e9liorer l\u2019efficacit\u00e9 et la performance cliniques et commerciales.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.veeva.com\/eu\/fr\/ressources\/iqvia-et-veeva-annoncent-des-partenariats-cliniques-et-commerciaux-a-long-terme-ainsi-que-la-resolution-de-leurs-litiges\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Veeva Systems Europe\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"IQVIA et Veeva annoncent des partenariats cliniques et commerciaux \u00e0 long terme ainsi que la r\u00e9solution de leurs litiges | Veeva Systems Europe\" \/>\n\t\t<meta property=\"og:description\" content=\"Ces accords de partenariats mondiaux ont pour objectif d\u2019aider les clients \u00e0 am\u00e9liorer l\u2019efficacit\u00e9 et la performance cliniques et commerciales.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.veeva.com\/eu\/fr\/ressources\/iqvia-et-veeva-annoncent-des-partenariats-cliniques-et-commerciaux-a-long-terme-ainsi-que-la-resolution-de-leurs-litiges\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.veeva.com\/eu\/wp-content\/uploads\/2025\/03\/resource-tile-news-340x240@2x.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.veeva.com\/eu\/wp-content\/uploads\/2025\/03\/resource-tile-news-340x240@2x.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-08-18T13:37:04+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-04-09T13:18:54+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"IQVIA et Veeva annoncent des partenariats cliniques et commerciaux \u00e0 long terme ainsi que la r\u00e9solution de leurs litiges | Veeva Systems Europe\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Ces accords de partenariats mondiaux ont pour objectif d\u2019aider les clients \u00e0 am\u00e9liorer l\u2019efficacit\u00e9 et la performance cliniques et commerciales.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.veeva.com\/eu\/wp-content\/uploads\/2025\/03\/resource-tile-news-340x240@2x.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/fr\\\/ressources\\\/iqvia-et-veeva-annoncent-des-partenariats-cliniques-et-commerciaux-a-long-terme-ainsi-que-la-resolution-de-leurs-litiges\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.veeva.com\\\/eu\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/fr\\\/ressources\\\/#listItem\",\"name\":\"Resources - FR\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/fr\\\/ressources\\\/#listItem\",\"position\":2,\"name\":\"Resources - FR\",\"item\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/fr\\\/ressources\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/resources-fr-canonical\\\/unique\\\/#listItem\",\"name\":\"Make Unique\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/resources-fr-canonical\\\/unique\\\/#listItem\",\"position\":3,\"name\":\"Make Unique\",\"item\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/resources-fr-canonical\\\/unique\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/fr\\\/ressources\\\/iqvia-et-veeva-annoncent-des-partenariats-cliniques-et-commerciaux-a-long-terme-ainsi-que-la-resolution-de-leurs-litiges\\\/#listItem\",\"name\":\"IQVIA et Veeva annoncent des partenariats cliniques et commerciaux \\u00e0 long terme ainsi que la r\\u00e9solution de leurs litiges\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/fr\\\/ressources\\\/#listItem\",\"name\":\"Resources - FR\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/fr\\\/ressources\\\/iqvia-et-veeva-annoncent-des-partenariats-cliniques-et-commerciaux-a-long-terme-ainsi-que-la-resolution-de-leurs-litiges\\\/#listItem\",\"position\":4,\"name\":\"IQVIA et Veeva annoncent des partenariats cliniques et commerciaux \\u00e0 long terme ainsi que la r\\u00e9solution de leurs litiges\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/resources-fr-canonical\\\/unique\\\/#listItem\",\"name\":\"Make Unique\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/#organization\",\"name\":\"Veeva Systems Europe\",\"description\":\"EU Site\",\"url\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/fr\\\/ressources\\\/iqvia-et-veeva-annoncent-des-partenariats-cliniques-et-commerciaux-a-long-terme-ainsi-que-la-resolution-de-leurs-litiges\\\/#webpage\",\"url\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/fr\\\/ressources\\\/iqvia-et-veeva-annoncent-des-partenariats-cliniques-et-commerciaux-a-long-terme-ainsi-que-la-resolution-de-leurs-litiges\\\/\",\"name\":\"IQVIA et Veeva annoncent des partenariats cliniques et commerciaux \\u00e0 long terme ainsi que la r\\u00e9solution de leurs litiges | Veeva Systems Europe\",\"description\":\"Ces accords de partenariats mondiaux ont pour objectif d\\u2019aider les clients \\u00e0 am\\u00e9liorer l\\u2019efficacit\\u00e9 et la performance cliniques et commerciales.\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/fr\\\/ressources\\\/iqvia-et-veeva-annoncent-des-partenariats-cliniques-et-commerciaux-a-long-terme-ainsi-que-la-resolution-de-leurs-litiges\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/IQVIA-and-Veeva_Resource-tile_340x240.png\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/fr\\\/ressources\\\/iqvia-et-veeva-annoncent-des-partenariats-cliniques-et-commerciaux-a-long-terme-ainsi-que-la-resolution-de-leurs-litiges\\\/#mainImage\",\"width\":680,\"height\":480,\"caption\":\"IQVIA and Veeva_Resource tile_340x240\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/fr\\\/ressources\\\/iqvia-et-veeva-annoncent-des-partenariats-cliniques-et-commerciaux-a-long-terme-ainsi-que-la-resolution-de-leurs-litiges\\\/#mainImage\"},\"datePublished\":\"2025-08-18T15:37:04+02:00\",\"dateModified\":\"2026-04-09T15:18:54+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/#website\",\"url\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/\",\"name\":\"Veeva Systems Europe\",\"description\":\"EU Site\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.veeva.com\\\/eu\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>IQVIA et Veeva annoncent des partenariats cliniques et commerciaux \u00e0 long terme ainsi que la r\u00e9solution de leurs litiges | Veeva Systems Europe<\/title>\n\n","aioseo_head_json":{"title":"IQVIA et Veeva annoncent des partenariats cliniques et commerciaux \u00e0 long terme ainsi que la r\u00e9solution de leurs litiges | Veeva Systems Europe","description":"Ces accords de partenariats mondiaux ont pour objectif d\u2019aider les clients \u00e0 am\u00e9liorer l\u2019efficacit\u00e9 et la performance cliniques et commerciales.","canonical_url":"https:\/\/www.veeva.com\/eu\/fr\/ressources\/iqvia-et-veeva-annoncent-des-partenariats-cliniques-et-commerciaux-a-long-terme-ainsi-que-la-resolution-de-leurs-litiges\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.veeva.com\/eu\/fr\/ressources\/iqvia-et-veeva-annoncent-des-partenariats-cliniques-et-commerciaux-a-long-terme-ainsi-que-la-resolution-de-leurs-litiges\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.veeva.com\/eu#listItem","position":1,"name":"Home","item":"https:\/\/www.veeva.com\/eu","nextItem":{"@type":"ListItem","@id":"https:\/\/www.veeva.com\/eu\/fr\/ressources\/#listItem","name":"Resources - FR"}},{"@type":"ListItem","@id":"https:\/\/www.veeva.com\/eu\/fr\/ressources\/#listItem","position":2,"name":"Resources - FR","item":"https:\/\/www.veeva.com\/eu\/fr\/ressources\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.veeva.com\/eu\/resources-fr-canonical\/unique\/#listItem","name":"Make Unique"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.veeva.com\/eu#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.veeva.com\/eu\/resources-fr-canonical\/unique\/#listItem","position":3,"name":"Make Unique","item":"https:\/\/www.veeva.com\/eu\/resources-fr-canonical\/unique\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.veeva.com\/eu\/fr\/ressources\/iqvia-et-veeva-annoncent-des-partenariats-cliniques-et-commerciaux-a-long-terme-ainsi-que-la-resolution-de-leurs-litiges\/#listItem","name":"IQVIA et Veeva annoncent des partenariats cliniques et commerciaux \u00e0 long terme ainsi que la r\u00e9solution de leurs litiges"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.veeva.com\/eu\/fr\/ressources\/#listItem","name":"Resources - FR"}},{"@type":"ListItem","@id":"https:\/\/www.veeva.com\/eu\/fr\/ressources\/iqvia-et-veeva-annoncent-des-partenariats-cliniques-et-commerciaux-a-long-terme-ainsi-que-la-resolution-de-leurs-litiges\/#listItem","position":4,"name":"IQVIA et Veeva annoncent des partenariats cliniques et commerciaux \u00e0 long terme ainsi que la r\u00e9solution de leurs litiges","previousItem":{"@type":"ListItem","@id":"https:\/\/www.veeva.com\/eu\/resources-fr-canonical\/unique\/#listItem","name":"Make Unique"}}]},{"@type":"Organization","@id":"https:\/\/www.veeva.com\/eu\/#organization","name":"Veeva Systems Europe","description":"EU Site","url":"https:\/\/www.veeva.com\/eu\/"},{"@type":"WebPage","@id":"https:\/\/www.veeva.com\/eu\/fr\/ressources\/iqvia-et-veeva-annoncent-des-partenariats-cliniques-et-commerciaux-a-long-terme-ainsi-que-la-resolution-de-leurs-litiges\/#webpage","url":"https:\/\/www.veeva.com\/eu\/fr\/ressources\/iqvia-et-veeva-annoncent-des-partenariats-cliniques-et-commerciaux-a-long-terme-ainsi-que-la-resolution-de-leurs-litiges\/","name":"IQVIA et Veeva annoncent des partenariats cliniques et commerciaux \u00e0 long terme ainsi que la r\u00e9solution de leurs litiges | Veeva Systems Europe","description":"Ces accords de partenariats mondiaux ont pour objectif d\u2019aider les clients \u00e0 am\u00e9liorer l\u2019efficacit\u00e9 et la performance cliniques et commerciales.","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/www.veeva.com\/eu\/#website"},"breadcrumb":{"@id":"https:\/\/www.veeva.com\/eu\/fr\/ressources\/iqvia-et-veeva-annoncent-des-partenariats-cliniques-et-commerciaux-a-long-terme-ainsi-que-la-resolution-de-leurs-litiges\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/www.veeva.com\/eu\/wp-content\/uploads\/2025\/08\/IQVIA-and-Veeva_Resource-tile_340x240.png","@id":"https:\/\/www.veeva.com\/eu\/fr\/ressources\/iqvia-et-veeva-annoncent-des-partenariats-cliniques-et-commerciaux-a-long-terme-ainsi-que-la-resolution-de-leurs-litiges\/#mainImage","width":680,"height":480,"caption":"IQVIA and Veeva_Resource tile_340x240"},"primaryImageOfPage":{"@id":"https:\/\/www.veeva.com\/eu\/fr\/ressources\/iqvia-et-veeva-annoncent-des-partenariats-cliniques-et-commerciaux-a-long-terme-ainsi-que-la-resolution-de-leurs-litiges\/#mainImage"},"datePublished":"2025-08-18T15:37:04+02:00","dateModified":"2026-04-09T15:18:54+02:00"},{"@type":"WebSite","@id":"https:\/\/www.veeva.com\/eu\/#website","url":"https:\/\/www.veeva.com\/eu\/","name":"Veeva Systems Europe","description":"EU Site","inLanguage":"en-US","publisher":{"@id":"https:\/\/www.veeva.com\/eu\/#organization"}}]},"og:locale":"en_US","og:site_name":"Veeva Systems Europe","og:type":"article","og:title":"IQVIA et Veeva annoncent des partenariats cliniques et commerciaux \u00e0 long terme ainsi que la r\u00e9solution de leurs litiges | Veeva Systems Europe","og:description":"Ces accords de partenariats mondiaux ont pour objectif d\u2019aider les clients \u00e0 am\u00e9liorer l\u2019efficacit\u00e9 et la performance cliniques et commerciales.","og:url":"https:\/\/www.veeva.com\/eu\/fr\/ressources\/iqvia-et-veeva-annoncent-des-partenariats-cliniques-et-commerciaux-a-long-terme-ainsi-que-la-resolution-de-leurs-litiges\/","og:image":"https:\/\/www.veeva.com\/eu\/wp-content\/uploads\/2025\/03\/resource-tile-news-340x240@2x.png","og:image:secure_url":"https:\/\/www.veeva.com\/eu\/wp-content\/uploads\/2025\/03\/resource-tile-news-340x240@2x.png","article:published_time":"2025-08-18T13:37:04+00:00","article:modified_time":"2026-04-09T13:18:54+00:00","twitter:card":"summary_large_image","twitter:title":"IQVIA et Veeva annoncent des partenariats cliniques et commerciaux \u00e0 long terme ainsi que la r\u00e9solution de leurs litiges | Veeva Systems Europe","twitter:description":"Ces accords de partenariats mondiaux ont pour objectif d\u2019aider les clients \u00e0 am\u00e9liorer l\u2019efficacit\u00e9 et la performance cliniques et commerciales.","twitter:image":"https:\/\/www.veeva.com\/eu\/wp-content\/uploads\/2025\/03\/resource-tile-news-340x240@2x.png"},"aioseo_meta_data":{"post_id":"86791","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"custom_image","og_image_url":"https:\/\/www.veeva.com\/eu\/wp-content\/uploads\/2025\/03\/resource-tile-news-340x240@2x.png","og_image_width":"0","og_image_height":"0","og_image_custom_url":"https:\/\/www.veeva.com\/eu\/wp-content\/uploads\/2025\/03\/resource-tile-news-340x240@2x.png","og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":true,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"limit_modified_date":false,"open_ai":"{\"title\":{\"suggestions\":[],\"usage\":0},\"description\":{\"suggestions\":[],\"usage\":0}}","created":"2025-08-20 13:33:16","updated":"2026-08-24 23:48:34","focus_keyword":null,"additional_keywords":null,"truseo_locale":null,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":"2026-08-24 23:48:34"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.veeva.com\/eu\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.veeva.com\/eu\/fr\/ressources\/\" title=\"Resources - FR\">Resources - FR<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.veeva.com\/eu\/resources-fr-canonical\/unique\/\" title=\"Make Unique\">Make Unique<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tIQVIA et Veeva annoncent des partenariats cliniques et commerciaux \u00e0 long terme ainsi que la r\u00e9solution de leurs litiges\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.veeva.com\/eu"},{"label":"Resources - FR","link":"https:\/\/www.veeva.com\/eu\/fr\/ressources\/"},{"label":"Make Unique","link":"https:\/\/www.veeva.com\/eu\/resources-fr-canonical\/unique\/"},{"label":"IQVIA et Veeva annoncent des partenariats cliniques et commerciaux \u00e0 long terme ainsi que la r\u00e9solution de leurs litiges","link":"https:\/\/www.veeva.com\/eu\/fr\/ressources\/iqvia-et-veeva-annoncent-des-partenariats-cliniques-et-commerciaux-a-long-terme-ainsi-que-la-resolution-de-leurs-litiges\/"}],"_links":{"self":[{"href":"https:\/\/www.veeva.com\/eu\/wp-json\/wp\/v2\/resources_fr\/86791","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.veeva.com\/eu\/wp-json\/wp\/v2\/resources_fr"}],"about":[{"href":"https:\/\/www.veeva.com\/eu\/wp-json\/wp\/v2\/types\/resources_fr"}],"version-history":[{"count":1,"href":"https:\/\/www.veeva.com\/eu\/wp-json\/wp\/v2\/resources_fr\/86791\/revisions"}],"predecessor-version":[{"id":86792,"href":"https:\/\/www.veeva.com\/eu\/wp-json\/wp\/v2\/resources_fr\/86791\/revisions\/86792"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.veeva.com\/eu\/wp-json\/wp\/v2\/media\/86688"}],"wp:attachment":[{"href":"https:\/\/www.veeva.com\/eu\/wp-json\/wp\/v2\/media?parent=86791"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}