{"id":48438,"date":"2020-03-27T13:48:11","date_gmt":"2020-03-27T17:48:11","guid":{"rendered":"http:\/\/www.veeva.com\/?page_id=48438"},"modified":"2026-06-15T16:06:08","modified_gmt":"2026-06-15T22:06:08","slug":"development-cloud","status":"publish","type":"page","link":"https:\/\/www.veeva.com\/la\/products\/development-cloud\/","title":{"rendered":"Veeva Development Cloud"},"content":{"rendered":"<link rel=\"stylesheet\" id=\"main-style-css\" href=\"https:\/\/www.veeva.com\/wp-content\/themes\/veeva2015\/assets\/css\/product-styles.css?v=4.3\" type=\"text\/css\" media=\"all\">\n<section class=\"block\">\n<div class=\"product-banner-hero\" style=\"background-image: url(&quot;https:\/\/www.veeva.com\/la\/wp-content\/uploads\/2020\/03\/Veeva-Development-Cloud-Hero.png&quot;);\">\n<div class=\"container\">\n<div class=\"row\">\n<div class=\"col-xs-12\">\n<div class=\"breadcrumbs\">\n\t\t\t\t\t\t<a href=\"\/br\/\">Home<\/a> \u00b7  <\/p>\n<p>\t <!-- get the nav url --><br \/>\n\t\t <a href=\"\/br\/products\/development-cloud\/\">Development Cloud<\/a> <\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"row table-row text-center\">\n<div class=\"col-xs-12\" style=\"text-align: center;\">\n<h2>Optimiza el desarrollo del producto<\/h2>\n<p>Elimina los silos e impulsa procesos integrales en las \u00e1reas cl\u00ednicas, de calidad, regulatorias y de seguridad.<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/section>\n<div class=\"product-container\" style=\"background-color: rgb(255, 255, 255);\">\n<div class=\"container\">\n<div class=\"row\">\n<div class=\"col-md-10 col-md-offset-1\">\n<h1>Veeva Development Cloud<\/h1>\n<p>\nVeeva Development Cloud re\u00fane las aplicaciones para las \u00e1reas cl\u00ednicas, regulatorias, de calidad y de seguridad para ayudar a las empresas a eliminar los silos e impulsar los procesos comerciales de principio a fin a lo largo del desarrollo del producto.<\/p>\n<p>\nHoy en d\u00eda, las aplicaciones de desarrollo del producto se encuentran aisladas y mal integradas. Contar con muchos sistemas crea ineficiencias y ralentiza los procesos comerciales cr\u00edticos. Veeva es la primera y la \u00fanica compa\u00f1\u00eda que ofrece un conjunto de aplicaciones unificadas en una sola plataforma en la nube a lo largo de todo el ciclo de vida del producto.\n<\/p>\n<p>\nCon todas las aplicaciones integradas en Veeva Vault Platform, las empresas pueden optimizar la informaci\u00f3n de desarrollo del producto en diversas regiones y departamentos para lograr una mejor eficiencia y cumplimiento.\n<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"row\">\n<div class=\"col-sm-12\">\n<div class=\"row\">\n<div class=\"col-sm-4  benefits\">\n<div style=\"padding-top: 30px;\">\n<h4>Mayor rapidez en la comercializaci\u00f3n<\/h4>\n<p>Mejora la eficiencia operativa al impulsar procesos comerciales de desarrollo del producto congruentes de principio a fin en un solo sistema.<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"col-sm-4  benefits\">\n<div style=\"padding-top: 30px;\">\n<h4>Alineaci\u00f3n global<\/h4>\n<p>Adquiere visibilidad en todas las sedes, sitios y pa\u00edses.<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"col-sm-4  benefits\">\n<div style=\"padding-top: 30px;\">\n<h4>Cumplimiento integral<\/h4>\n<p>Logra obtener calidad confiable en la informaci\u00f3n a lo largo del ciclo de vida del desarrollo.<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<style>\n\t.product-container .col-padding {\n\t\tpadding-left:7px;\n\t\tpadding-right:7px;\n\t}\n\t.product-container .cloud-bar .title {\n\tfont-weight:400;font-size:17px;padding-bottom:7px;white-space:nowrap;\n\tmargin-top:10px;\n\t}\n\t.product-container .cloud-bar .icon {\n\tpadding:14px;background-color:#fbb912;\n\t}<\/p>\n<p>\t@media screen and (max-width: 767px) {\n.product-container .cloud-bar .title {\n\tfont-weight:400;font-size:15px;padding-bottom:5px;white-space:nowrap;\n\tmargin-top:10px;\n\t}\n}\n\t<\/style>\n<div class=\"row cloud-bar\" style=\"margin-top: 50px;\">\n<div class=\"col-xs-6 col-sm-4 col-md-5ths col-padding\">\n<div class=\"title\">Clinical Data Management<\/div>\n<div class=\"icon\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.veeva.com\/wp-content\/themes\/veeva2015\/assets\/img\/products\/Dev-Cloud-Clinical-Data-Management-Icon.png\" alt=\"Clinical-Data-Management-Icon\">\n\t\t\t\t\t\t<\/div>\n<\/p><\/div>\n<div class=\"col-xs-6 col-sm-4 col-md-5ths col-padding\">\n<div class=\"title\">Clinical Operations<\/div>\n<div class=\"icon\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.veeva.com\/wp-content\/themes\/veeva2015\/assets\/img\/products\/Dev-Cloud-Clinical-Operations-Icon.png\" alt=\"Clinical-Data-Management-Icon\">\n\t\t\t\t\t\t<\/div>\n<\/p><\/div>\n<div class=\"col-xs-6 col-sm-4 col-md-5ths col-padding\">\n<div class=\"title\">Quality<\/div>\n<div class=\"icon\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.veeva.com\/wp-content\/themes\/veeva2015\/assets\/img\/products\/Dev-Cloud-Quality-Icon.png\" alt=\"Clinical-Data-Management-Icon\">\n\t\t\t\t\t\t<\/div>\n<\/p><\/div>\n<div class=\"col-xs-6 col-sm-4  col-sm-offset-2 col-md-5ths col-md-offset-0 col-padding\">\n<div class=\"title\">Regulatory<\/div>\n<div class=\"icon\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.veeva.com\/wp-content\/themes\/veeva2015\/assets\/img\/products\/Dev-Cloud-Regulatory-Icon.png\" alt=\"Clinical-Data-Management-Icon\">\n\t\t\t\t\t\t<\/div>\n<\/p><\/div>\n<div class=\"col-xs-6 col-xs-offset-3 col-sm-4 col-sm-offset-0 col-md-5ths col-padding\">\n<div class=\"title\">Safety<\/div>\n<div class=\"icon\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.veeva.com\/wp-content\/themes\/veeva2015\/assets\/img\/products\/Dev-Cloud-Safety-Icon.png\" alt=\"Clinical-Data-Management-Icon\">\n\t\t\t\t\t\t<\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"row cloud-bar\" style=\"margin-top: 14px;\">\n<div class=\"col-sm-12 col-padding\">\n<div class=\"icon\" style=\"background-color: rgb(137, 138, 141); padding: 16px;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.veeva.com\/wp-content\/themes\/veeva2015\/assets\/img\/products\/Dev-Cloud-Vault-Platform-Logo.png\" alt=\"Clinical-Data-Management-Icon\">\n\t\t\t\t\t\t<\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/div>\n<p><!-- FEATURES -->\t<\/p>\n<style>\n@media screen and (max-width: 991px) {\n.product-container .img-responsive {\nmargin: auto;\nmargin-bottom: 30px;\nmargin-top: 25px;\n}\n}\n.prod-grid p {\nfont-size: 16px;\nline-height: 25px;\nmargin-top:10px;\n}\n.prod-grid a {\nwhite-space:nowrap;\n}\n.prod-grid .col-sm-6 {\nmargin-top:25px\n}\n@media (min-width: 768px) and (max-width: 5000px) {\n  .prod-grid .col-sm-6:nth-child(2n+1) {\n    clear: left;\n  }\n}<\/p>\n<p>@media screen and (max-width: 767px) {\n.prod-grid p {<\/p>\n<p>margin-top:3px;\n}\n.prod-grid .col-sm-6 {\nmargin-top:20px\n}\n}<\/p>\n<\/style>\n<div class=\"product-container\" style=\"background-color: rgb(244, 244, 244);\">\n<div class=\"container\">\n\t\t<!-- feature 1 -->\t<\/p>\n<div class=\"row suite-features text-left\">\n<div class=\"col-md-6\">\n<h2>Veeva Connections<\/h2>\n<div class=\"visible-xs visible-sm\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.veeva.com\/wp-content\/uploads\/2021\/05\/Laptop_Vault-Connections_588x370.png\" alt=\"Veeva Connections\" class=\"img-responsive  \">\n\t\t\t\t\t\t\t\t\t\t<\/div>\n<p>Veeva Connections son inclusiones que ofrece Veeva y que permiten transferir sin ning\u00fan inconveniente informaci\u00f3n y documentos entre aplica\u00e7\u00f5es de cl\u00ednicas, calidad, regulatorias y de farmacovigilancia. Est\u00e1n dise\u00f1adas para optimizar procesos empresariales multifuncionales al eliminar silos y proporcionar una mayor visibilidad, as\u00ed como automatizar las tareas manuales. Para obtener mayor informaci\u00f3n acerca de Veeva Connections, visita nuestro Centro de recursos.<\/p>\n<div class=\"row prod-grid\">\n<div class=\"col-sm-12\">\nVeeva Clinical Operations to RIM Connection<\/p>\n<p>Comparte informaci\u00f3n y documentos acerca del producto, el estudio y el centro. <\/p>\n<\/div>\n<div class=\"col-sm-12\">\n\tVeeva Quality  to RIM Connection<\/p>\n<p>Acelera el control de cambios y la gesti\u00f3n de las modificaciones.<\/p>\n<\/div>\n<div class=\"col-sm-12\">\n\tVeeva CDMS to Clinical  Operations Connection<\/p>\n<p>Obt\u00e9n actualizaciones en tiempo real acerca de la inscripci\u00f3n del centro.<\/p>\n<\/div><\/div>\n<\/p><\/div>\n<div class=\"col-md-6 hidden-xs hidden-sm\">\n  \t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.veeva.com\/wp-content\/uploads\/2021\/05\/Laptop_Vault-Connections_588x370.png\" alt=\"Veeva Connections\" class=\"img-responsive  \">\n\t\t\t\t\t  \t\t\t<\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/div>\n<div class=\"product-container\" style=\"background-color: rgb(255, 255, 255);\">\n<div class=\"container\">\n\t\t<!-- feature 2 -->\t<\/p>\n<div class=\"row suite-features text-left\">\n<div class=\"col-md-6 hidden-xs hidden-sm\">\n  \t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.veeva.com\/wp-content\/themes\/veeva2015\/assets\/img\/products\/Development-Cloud-Suite-5-576px.png\" alt=\"Gesti\u00f3n de datos cl\u00ednicos\" class=\"img-responsive  \">\n\t\t\t\t\t  \t\t\t<\/div>\n<div class=\"col-md-6\">\n<h2>Gesti\u00f3n de datos cl\u00ednicos<\/h2>\n<div class=\"visible-xs visible-sm\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.veeva.com\/wp-content\/themes\/veeva2015\/assets\/img\/products\/Development-Cloud-Suite-5-576px.png\" alt=\"Gesti\u00f3n de datos cl\u00ednicos\" class=\"img-responsive  \">\n\t\t\t\t\t\t\t\t\t\t<\/div>\n<p>Acelera los plazos del estudio por medio de aplicaciones innovadoras y modernas para obtener datos cl\u00ednicos. Veeva Clinical Data redefine la gesti\u00f3n de datos para ayudar a los equipos cl\u00ednicos a manejar los ensayos actuales con agilidad y rapidez.<\/p>\n<div class=\"row prod-grid\">\n<div class=\"col-sm-6\">\n\t<a href=\"\/la\/products\/vault-edc\/\" class=\"after-arrow-orange\">Veeva EDC<\/a><\/p>\n<p>Recolecta, limpia y revisa los datos de los estudios<\/p>\n<\/div>\n<div class=\"col-sm-6\">\n\t<a href=\"\/la\/products\/vault-coder\/\" class=\"after-arrow-orange\">Veeva Coder<\/a><\/p>\n<p>Codifica r\u00e1pidamente los t\u00e9rminos cl\u00ednicos.<\/p>\n<\/div>\n<div class=\"col-sm-6\">\n\t<a href=\"\/la\/products\/veeva-cdb\/\" class=\"after-arrow-orange\">Veeva CDB<\/a><\/p>\n<p>Gestiona todos los datos paralelos de los estudios.<\/p>\n<\/div><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/div>\n<div class=\"product-container\" style=\"background-color: rgb(244, 244, 244);\">\n<div class=\"container\">\n\t\t<!-- feature 3 -->\t<\/p>\n<div class=\"row suite-features text-left\">\n<div class=\"col-md-6\">\n<h2>Veeva Clinical Operations<\/h2>\n<div class=\"visible-xs visible-sm\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.veeva.com\/wp-content\/themes\/veeva2015\/assets\/img\/products\/Development-Cloud-Suite-4-576px.png\" alt=\"Veeva Clinical Operations\" class=\"img-responsive  \">\n\t\t\t\t\t\t\t\t\t\t<\/div>\n<p>El \u00fanico conjunto de aplicaciones unificadas para operaciones cl\u00ednicas desde una sola plataforma en la nube.<\/p>\n<p>El primer y \u00fanico conjunto de aplicaciones unificadas de operaciones cl\u00ednicas de la industria, incluyendo study start-up, eTMF, CTMS<span>, y payments<\/span> desde una sola plataforma en la nube para acelerar la ejecuci\u00f3n de los ensayos y tener visibilidad en tiempo real.<\/p>\n<div class=\"row prod-grid\">\n<div class=\"col-sm-6\">\n\t<a href=\"\/la\/products\/vault-study-startup\/\" class=\"after-arrow-orange\">Veeva Study Startup<\/a><\/p>\n<p>Acelera el tiempo de activaci\u00f3n de los sitios. <\/p>\n<\/div>\n<div class=\"col-sm-6\">\n\t<a href=\"\/la\/products\/vault-ctms\/\" class=\"after-arrow-orange\">Veeva CTMS<\/a><\/p>\n<p>Habilita la gesti\u00f3n proactiva de ensayos.<\/p>\n<\/div>\n<div class=\"col-sm-6\">\n\t<a href=\"\/la\/products\/vault-etmf\/\" class=\"after-arrow-orange\">Veeva eTMF<\/a><\/p>\n<p>Habilita el eTMF activo para la preparaci\u00f3n de inspecciones en tiempo real.<\/p>\n<\/div>\n<div class=\"col-sm-6\">\n\t<a href=\"\/la\/products\/vault-payments\/\" class=\"after-arrow-orange\">Veeva Payments<\/a><\/p>\n<p>Paga de forma m\u00e1s r\u00e1pida a los centros de investigaci\u00f3n cl\u00ednica.<\/p>\n<\/div>\n<div class=\"col-sm-6\">\n\t<a href=\"\/la\/products\/vault-site-connect\/\" class=\"after-arrow-orange\">Veeva Site Connect<\/a><\/p>\n<p>Automatiza informaci\u00f3n al compartir los ensayos cl\u00ednicos.<\/p>\n<\/div><\/div>\n<\/p><\/div>\n<div class=\"col-md-6 hidden-xs hidden-sm\">\n  \t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.veeva.com\/wp-content\/themes\/veeva2015\/assets\/img\/products\/Development-Cloud-Suite-4-576px.png\" alt=\"Veeva Clinical Operations\" class=\"img-responsive  \">\n\t\t\t\t\t  \t\t\t<\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/div>\n<div class=\"product-container\" style=\"background-color: rgb(255, 255, 255);\">\n<div class=\"container\">\n\t\t<!-- feature 4 -->\t<\/p>\n<div class=\"row suite-features text-left\">\n<div class=\"col-md-6 hidden-xs hidden-sm\">\n  \t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.veeva.com\/wp-content\/themes\/veeva2015\/assets\/img\/products\/Development-Cloud-Suite-3-576px.png\" alt=\"Veeva Quality\" class=\"img-responsive  \">\n\t\t\t\t\t  \t\t\t<\/div>\n<div class=\"col-md-6\">\n<h2>Veeva Quality<\/h2>\n<div class=\"visible-xs visible-sm\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.veeva.com\/wp-content\/themes\/veeva2015\/assets\/img\/products\/Development-Cloud-Suite-3-576px.png\" alt=\"Veeva Quality\" class=\"img-responsive  \">\n\t\t\t\t\t\t\t\t\t\t<\/div>\n<p>Moderniza el control de calidad a la vez que impulsa el cumplimiento y la innovaci\u00f3n operacional.<\/p>\n<p>Gestiona sin problemas tus procesos de calidad y el contenido por medio del conjunto de aplicaciones de Veeva Quality. Todas las partes deben tener acceso a una sola fuente fidedigna, lo que permite tener una mayor visibilidad y control.<\/p>\n<div class=\"row prod-grid\">\n<div class=\"col-sm-6\">\n\t<a href=\"\/la\/products\/vault-qms\/\" class=\"after-arrow-orange\">Veeva QMS<\/a><\/p>\n<p>Gestiona f\u00e1cilmente todos los procesos de calidad<\/p>\n<\/div>\n<div class=\"col-sm-6\">\n\t<a href=\"\/la\/products\/vault-product-surveillance\/\" class=\"after-arrow-orange\">Veeva Product Surveillance<\/a><\/p>\n<p>Simplifica el seguimiento de dispositivos m\u00e9dicos despu\u00e9s de la comercializaci\u00f3n.<\/p>\n<\/div>\n<div class=\"col-sm-6\">\n\t<a href=\"\/la\/products\/vault-qualitydocs\/\" class=\"after-arrow-orange\">Veeva QualityDocs<\/a><\/p>\n<p>Controla todos los documentos de GxP.<\/p>\n<\/div>\n<div class=\"col-sm-6\">\n\t<a href=\"\/la\/products\/vault-station-manager\/\" class=\"after-arrow-orange\">Veeva Station Manager<\/a><\/p>\n<p>Entrega el contenido correcto al departamento de compras.<\/p>\n<\/div>\n<div class=\"col-sm-6\">\n\t<a href=\"\/la\/products\/vault-training\/\" class=\"after-arrow-orange\">Veeva Training<\/a><\/p>\n<p>Garantiza el cumplimiento y calificaciones en funci\u00f3n de los cargos.<\/p>\n<\/div><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/div>\n<div class=\"product-container\" style=\"background-color: rgb(244, 244, 244);\">\n<div class=\"container\">\n\t\t<!-- feature 5 -->\t<\/p>\n<div class=\"row suite-features text-left\">\n<div class=\"col-md-6\">\n<h2>Veeva RIM<\/h2>\n<div class=\"visible-xs visible-sm\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.veeva.com\/wp-content\/themes\/veeva2015\/assets\/img\/products\/Development-Cloud-Suite-2-576px.png\" alt=\"Veeva RIM\" class=\"img-responsive  \">\n\t\t\t\t\t\t\t\t\t\t<\/div>\n<p>Aporta velocidad y agilidad a tu equipo de regulaci\u00f3n mediante un RIM unificado.<\/p>\n<p>\nGestiona la planeaci\u00f3n, ejecuci\u00f3n y supervisi\u00f3n de todas las actividades regulatorias desde una sola plataforma RIM unificada.\n<\/p>\n<div class=\"row prod-grid\">\n<div class=\"col-sm-6\">\n\t<a href=\"\/la\/products\/vault-registrations\/\" class=\"after-arrow-orange\">Veeva Registrations<\/a><\/p>\n<p>Gestiona los registros del producto a nivel mundial.<\/p>\n<\/div>\n<div class=\"col-sm-6\">\n\t<a href=\"\/la\/products\/vault-submissions-publishing\/\" class=\"after-arrow-orange\">Veeva Submissions Publishing<\/a><\/p>\n<p>Automatiza las publicaciones durante el desarrollo del sometimiento.<\/p>\n<\/div>\n<div class=\"col-sm-6\">\n\t<a href=\"\/la\/products\/vault-submissions\/\" class=\"after-arrow-orange\">Veeva Submissions<\/a><\/p>\n<p>Agiliza el desarrollo del sometimiento.<\/p>\n<\/div>\n<div class=\"col-sm-6\">\n\t<a href=\"\/la\/products\/vault-submissions-archive\/\" class=\"after-arrow-orange\">Veeva Submissions Archive<\/a><\/p>\n<p>Conserva los dossiers publicados de forma segura en la nube.<\/p>\n<\/div><\/div>\n<\/p><\/div>\n<div class=\"col-md-6 hidden-xs hidden-sm\">\n  \t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.veeva.com\/wp-content\/themes\/veeva2015\/assets\/img\/products\/Development-Cloud-Suite-2-576px.png\" alt=\"Veeva RIM\" class=\"img-responsive  \">\n\t\t\t\t\t  \t\t\t<\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/div>\n<div class=\"product-container\" style=\"background-color: rgb(255, 255, 255);\">\n<div class=\"container\">\n\t\t<!-- feature 6 -->\t<\/p>\n<div class=\"row suite-features text-left\">\n<div class=\"col-md-6 hidden-xs hidden-sm\">\n  \t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.veeva.com\/wp-content\/themes\/veeva2015\/assets\/img\/products\/Development-Cloud-Suite-1-576px.png\" alt=\"Veeva Safety\" class=\"img-responsive  \">\n\t\t\t\t\t  \t\t\t<\/div>\n<div class=\"col-md-6\">\n<h2>Veeva Safety<\/h2>\n<div class=\"visible-xs visible-sm\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.veeva.com\/wp-content\/themes\/veeva2015\/assets\/img\/products\/Development-Cloud-Suite-1-576px.png\" alt=\"Veeva Safety\" class=\"img-responsive  \">\n\t\t\t\t\t\t\t\t\t\t<\/div>\n<p>Veeva Safety es la \u00fanica aplicaci\u00f3n moderna para la recolecci\u00f3n, gesti\u00f3n y supervisi\u00f3n en tiempo real de eventos adversos.<\/p>\n<div class=\"row prod-grid\">\n<div class=\"col-sm-6\">\n\t<a href=\"\/la\/products\/vault-safety\/\" class=\"after-arrow-orange\">Veeva Safety<\/a><\/p>\n<p>Gestiona y supervisa en tiempo real los eventos adversos.<\/p>\n<\/div>\n<div class=\"col-sm-6\">\n\t<a href=\"\/la\/products\/vault-safetydocs\/\" class=\"after-arrow-orange\">Veeva SafetyDocs<\/a><\/p>\n<p>Gestiona centralmente el contenido de farmacovigilancia.<\/p>\n<\/div>\n<div class=\"col-sm-6\">\n\t<a href=\"\/la\/products\/vault-signal\/\" class=\"after-arrow-orange\">Veeva Signal<\/a><\/p>\n<p>Gestiona las se\u00f1ales desde la detecci\u00f3n hasta la evaluaci\u00f3n y mitigaci\u00f3n de riesgos.<\/p>\n<\/div><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/div>\n<p><!-- END FEATURES -->\t<\/p>\n<div class=\"product-container customer-logos\" style=\"background-color: rgb(255, 255, 255);\">\n<div class=\"container\">\n<div class=\"wrapper\">\n<div class=\"row\">\n<div class=\"col-sm-12 text-center\">\n<h2>Las mejores empresas utilizan Veeva<\/h2>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"row\">\n<div class=\"col-sm-12 text-center\">\n          \t\t<img decoding=\"async\" src=\"https:\/\/www.veeva.com\/wp-content\/themes\/veeva2015\/assets\/img\/products\/suite-logos\/Aeglea-70px.png\" alt=\"Aeglea-Logo\"><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.veeva.com\/wp-content\/themes\/veeva2015\/assets\/img\/products\/suite-logos\/AstraZeneca-70px.png\" alt=\"AstraZeneca-Logo\"><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.veeva.com\/wp-content\/themes\/veeva2015\/assets\/img\/products\/suite-logos\/Leo-70px.png\" alt=\"Leo-Logo\"><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.veeva.com\/wp-content\/themes\/veeva2015\/assets\/img\/products\/suite-logos\/Lilly-70px.png\" alt=\"Lilly-Logo\"><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.veeva.com\/wp-content\/themes\/veeva2015\/assets\/img\/products\/suite-logos\/Merck-70px.png\" alt=\"Merck-Logo\"><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.veeva.com\/wp-content\/themes\/veeva2015\/assets\/img\/products\/suite-logos\/Tesaro-70px.png\" alt=\"Tesaro-Logo\">          \t\t<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/div>\n<div class=\"product-container\" id=\"demo\" style=\"background-color: rgb(235, 154, 63);\">\n<div class=\"container\">\n<div id=\"carousel-video\" class=\"carousel slide\" data-interval=\"false\">\n<div class=\"carousel-inner\" role=\"listbox\">\n<div class=\"item active\">\n<div class=\"row\">\n<div class=\"col-sm-10 col-sm-offset-1 text-center\">\n<h2>Veeva Development Cloud <\/h2>\n<script src=\"https:\/\/fast.wistia.com\/embed\/medias\/jauo5bd1t9.jsonp\" data-cookieconsent=\"ignore\" async><\/script><script src=\"https:\/\/fast.wistia.com\/assets\/external\/E-v1.js\" data-cookieconsent=\"ignore\" async><\/script><div class=\"wistia_responsive_padding\" style=\"padding:56.25% 0 0 0;position:relative;\"><div class=\"wistia_responsive_wrapper\" style=\"height:100%;left:0;position:absolute;top:0;width:100%;\"><div class=\"wistia_embed wistia_async_jauo5bd1t9 videoFoam=true\" style=\"height:100%;position:relative;width:100%\"><div class=\"wistia_swatch\" style=\"height:100%;left:0;opacity:0;overflow:hidden;position:absolute;top:0;transition:opacity 200ms;width:100%;\"><img decoding=\"async\" src=\"https:\/\/fast.wistia.com\/embed\/medias\/jauo5bd1t9\/swatch\" style=\"filter:blur(5px);height:100%;object-fit:contain;width:100%;\" alt=\"\" aria-hidden=\"true\" onload=\"this.parentNode.style.opacity=1;\" \/><\/div><\/div><\/div><\/div><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Vault Development Cloud brings together applications for clinical, regulatory, and quality to drive end-to-end business processes across product development.<\/p>\n","protected":false},"author":80,"featured_media":48454,"parent":20394,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/veeva-2024.full-page.php","meta":{"footnotes":""},"class_list":["post-48438","page","type-page","status-publish","has-post-thumbnail","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Home \u00b7 Development Cloud Optimiza el desarrollo del producto Elimina los silos e impulsa procesos integrales en las \u00e1reas cl\u00ednicas, de calidad, regulatorias y de seguridad. Veeva Development Cloud Veeva Development Cloud re\u00fane las aplicaciones para las \u00e1reas cl\u00ednicas, regulatorias, de calidad y de seguridad para ayudar a las empresas a eliminar los silos e\" \/>\n\t<meta name=\"robots\" content=\"max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.veeva.com\/la\/products\/development-cloud\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Veeva Systems\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Veeva Development Cloud | Veeva\" \/>\n\t\t<meta property=\"og:description\" content=\"Home \u00b7 Development Cloud Optimiza el desarrollo del producto Elimina los silos e impulsa procesos integrales en las \u00e1reas cl\u00ednicas, de calidad, regulatorias y de seguridad. Veeva Development Cloud Veeva Development Cloud re\u00fane las aplicaciones para las \u00e1reas cl\u00ednicas, regulatorias, de calidad y de seguridad para ayudar a las empresas a eliminar los silos e\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.veeva.com\/la\/products\/development-cloud\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.veeva.com\/wp-content\/uploads\/2020\/08\/Generic-Social-Banners_v3_Veeva-Generic.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.veeva.com\/wp-content\/uploads\/2020\/08\/Generic-Social-Banners_v3_Veeva-Generic.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-03-27T17:48:11+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-06-15T22:06:08+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Veeva Development Cloud | Veeva\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Home \u00b7 Development Cloud Optimiza el desarrollo del producto Elimina los silos e impulsa procesos integrales en las \u00e1reas cl\u00ednicas, de calidad, regulatorias y de seguridad. Veeva Development Cloud Veeva Development Cloud re\u00fane las aplicaciones para las \u00e1reas cl\u00ednicas, regulatorias, de calidad y de seguridad para ayudar a las empresas a eliminar los silos e\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.veeva.com\/wp-content\/uploads\/2020\/08\/Generic-Social-Banners_v3_Veeva-Generic.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/la\\\/products\\\/development-cloud\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/la#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.veeva.com\\\/la\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/la\\\/products\\\/#listItem\",\"name\":\"Products\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/la\\\/products\\\/#listItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\\\/\\\/www.veeva.com\\\/la\\\/products\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/la\\\/products\\\/development-cloud\\\/#listItem\",\"name\":\"Veeva Development Cloud\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/la#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/la\\\/products\\\/development-cloud\\\/#listItem\",\"position\":3,\"name\":\"Veeva Development Cloud\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/la\\\/products\\\/#listItem\",\"name\":\"Products\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/la\\\/#organization\",\"name\":\"Veeva\",\"url\":\"https:\\\/\\\/www.veeva.com\\\/la\\\/\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/la\\\/products\\\/development-cloud\\\/#webpage\",\"url\":\"https:\\\/\\\/www.veeva.com\\\/la\\\/products\\\/development-cloud\\\/\",\"name\":\"Veeva Development Cloud | Veeva\",\"description\":\"Home \\u00b7 Development Cloud Optimiza el desarrollo del producto Elimina los silos e impulsa procesos integrales en las \\u00e1reas cl\\u00ednicas, de calidad, regulatorias y de seguridad. Veeva Development Cloud Veeva Development Cloud re\\u00fane las aplicaciones para las \\u00e1reas cl\\u00ednicas, regulatorias, de calidad y de seguridad para ayudar a las empresas a eliminar los silos e\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.veeva.com\\\/la\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.veeva.com\\\/la\\\/products\\\/development-cloud\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.veeva.com\\\/la\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Veeva-Development-Cloud-Hero.png\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/la\\\/products\\\/development-cloud\\\/#mainImage\",\"width\":1580,\"height\":450},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.veeva.com\\\/la\\\/products\\\/development-cloud\\\/#mainImage\"},\"datePublished\":\"2020-03-27T13:48:11-06:00\",\"dateModified\":\"2026-06-15T16:06:08-06:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.veeva.com\\\/la\\\/#website\",\"url\":\"https:\\\/\\\/www.veeva.com\\\/la\\\/\",\"name\":\"Veeva\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.veeva.com\\\/la\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Veeva Development Cloud | Veeva<\/title>\n\n","aioseo_head_json":{"title":"Veeva Development Cloud | Veeva","description":"Home \u00b7 Development Cloud Optimiza el desarrollo del producto Elimina los silos e impulsa procesos integrales en las \u00e1reas cl\u00ednicas, de calidad, regulatorias y de seguridad. Veeva Development Cloud Veeva Development Cloud re\u00fane las aplicaciones para las \u00e1reas cl\u00ednicas, regulatorias, de calidad y de seguridad para ayudar a las empresas a eliminar los silos e","canonical_url":"https:\/\/www.veeva.com\/la\/products\/development-cloud\/","robots":"max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.veeva.com\/la\/products\/development-cloud\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.veeva.com\/la#listItem","position":1,"name":"Home","item":"https:\/\/www.veeva.com\/la","nextItem":{"@type":"ListItem","@id":"https:\/\/www.veeva.com\/la\/products\/#listItem","name":"Products"}},{"@type":"ListItem","@id":"https:\/\/www.veeva.com\/la\/products\/#listItem","position":2,"name":"Products","item":"https:\/\/www.veeva.com\/la\/products\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.veeva.com\/la\/products\/development-cloud\/#listItem","name":"Veeva Development Cloud"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.veeva.com\/la#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.veeva.com\/la\/products\/development-cloud\/#listItem","position":3,"name":"Veeva Development Cloud","previousItem":{"@type":"ListItem","@id":"https:\/\/www.veeva.com\/la\/products\/#listItem","name":"Products"}}]},{"@type":"Organization","@id":"https:\/\/www.veeva.com\/la\/#organization","name":"Veeva","url":"https:\/\/www.veeva.com\/la\/"},{"@type":"WebPage","@id":"https:\/\/www.veeva.com\/la\/products\/development-cloud\/#webpage","url":"https:\/\/www.veeva.com\/la\/products\/development-cloud\/","name":"Veeva Development Cloud | Veeva","description":"Home \u00b7 Development Cloud Optimiza el desarrollo del producto Elimina los silos e impulsa procesos integrales en las \u00e1reas cl\u00ednicas, de calidad, regulatorias y de seguridad. Veeva Development Cloud Veeva Development Cloud re\u00fane las aplicaciones para las \u00e1reas cl\u00ednicas, regulatorias, de calidad y de seguridad para ayudar a las empresas a eliminar los silos e","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/www.veeva.com\/la\/#website"},"breadcrumb":{"@id":"https:\/\/www.veeva.com\/la\/products\/development-cloud\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/www.veeva.com\/la\/wp-content\/uploads\/2020\/03\/Veeva-Development-Cloud-Hero.png","@id":"https:\/\/www.veeva.com\/la\/products\/development-cloud\/#mainImage","width":1580,"height":450},"primaryImageOfPage":{"@id":"https:\/\/www.veeva.com\/la\/products\/development-cloud\/#mainImage"},"datePublished":"2020-03-27T13:48:11-06:00","dateModified":"2026-06-15T16:06:08-06:00"},{"@type":"WebSite","@id":"https:\/\/www.veeva.com\/la\/#website","url":"https:\/\/www.veeva.com\/la\/","name":"Veeva","inLanguage":"en-US","publisher":{"@id":"https:\/\/www.veeva.com\/la\/#organization"}}]},"og:locale":"en_US","og:site_name":"Veeva Systems","og:type":"article","og:title":"Veeva Development Cloud | Veeva","og:description":"Home \u00b7 Development Cloud Optimiza el desarrollo del producto Elimina los silos e impulsa procesos integrales en las \u00e1reas cl\u00ednicas, de calidad, regulatorias y de seguridad. Veeva Development Cloud Veeva Development Cloud re\u00fane las aplicaciones para las \u00e1reas cl\u00ednicas, regulatorias, de calidad y de seguridad para ayudar a las empresas a eliminar los silos e","og:url":"https:\/\/www.veeva.com\/la\/products\/development-cloud\/","og:image":"https:\/\/www.veeva.com\/wp-content\/uploads\/2020\/08\/Generic-Social-Banners_v3_Veeva-Generic.png","og:image:secure_url":"https:\/\/www.veeva.com\/wp-content\/uploads\/2020\/08\/Generic-Social-Banners_v3_Veeva-Generic.png","article:published_time":"2020-03-27T17:48:11+00:00","article:modified_time":"2026-06-15T22:06:08+00:00","twitter:card":"summary","twitter:title":"Veeva Development Cloud | Veeva","twitter:description":"Home \u00b7 Development Cloud Optimiza el desarrollo del producto Elimina los silos e impulsa procesos integrales en las \u00e1reas cl\u00ednicas, de calidad, regulatorias y de seguridad. Veeva Development Cloud Veeva Development Cloud re\u00fane las aplicaciones para las \u00e1reas cl\u00ednicas, regulatorias, de calidad y de seguridad para ayudar a las empresas a eliminar los silos e","twitter:image":"https:\/\/www.veeva.com\/wp-content\/uploads\/2020\/08\/Generic-Social-Banners_v3_Veeva-Generic.png"},"aioseo_meta_data":{"post_id":"48438","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"article","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"summary","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"limit_modified_date":false,"open_ai":"{\"title\":{\"suggestions\":[],\"usage\":0},\"description\":{\"suggestions\":[],\"usage\":0}}","created":"2022-11-09 23:09:24","updated":"2026-08-20 22:30:37","focus_keyword":null,"additional_keywords":null,"truseo_locale":null,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":"2026-08-20 22:30:37"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.veeva.com\/la\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.veeva.com\/la\/products\/\" title=\"Products\">Products<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tVeeva Development Cloud\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.veeva.com\/la"},{"label":"Products","link":"https:\/\/www.veeva.com\/la\/products\/"},{"label":"Veeva Development Cloud","link":"https:\/\/www.veeva.com\/la\/products\/development-cloud\/"}],"_links":{"self":[{"href":"https:\/\/www.veeva.com\/la\/wp-json\/wp\/v2\/pages\/48438","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.veeva.com\/la\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.veeva.com\/la\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.veeva.com\/la\/wp-json\/wp\/v2\/users\/80"}],"replies":[{"embeddable":true,"href":"https:\/\/www.veeva.com\/la\/wp-json\/wp\/v2\/comments?post=48438"}],"version-history":[{"count":5,"href":"https:\/\/www.veeva.com\/la\/wp-json\/wp\/v2\/pages\/48438\/revisions"}],"predecessor-version":[{"id":60577,"href":"https:\/\/www.veeva.com\/la\/wp-json\/wp\/v2\/pages\/48438\/revisions\/60577"}],"up":[{"embeddable":true,"href":"https:\/\/www.veeva.com\/la\/wp-json\/wp\/v2\/pages\/20394"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.veeva.com\/la\/wp-json\/wp\/v2\/media\/48454"}],"wp:attachment":[{"href":"https:\/\/www.veeva.com\/la\/wp-json\/wp\/v2\/media?parent=48438"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}